{"id":2620,"count":0,"description":"","link":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/","name":"Flora and fauna identification guides","slug":"flora-and-fauna-identification-guides","taxonomy":"product_cat","parent":2599,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Flora and fauna identification guides Archivi - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flora and fauna identification guides Archivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/books-marine-biology\\\/flora-and-fauna-identification-guides\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/books-marine-biology\\\/flora-and-fauna-identification-guides\\\/\",\"name\":\"Flora and fauna identification guides Archivi - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/books-marine-biology\\\/flora-and-fauna-identification-guides\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/books-marine-biology\\\/flora-and-fauna-identification-guides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Books and DVDs\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Books\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Adults\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Books: Marine biology\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/categoria-prodotto\\\/books-and-dvds\\\/books\\\/adults-books\\\/books-marine-biology\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Flora and fauna identification guides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Flora and fauna identification guides Archivi - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/","og_locale":"en_US","og_type":"article","og_title":"Flora and fauna identification guides Archivi","og_url":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/","og_site_name":"Libreria del Mare","og_image":[{"width":600,"height":162,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/","url":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/","name":"Flora and fauna identification guides Archivi - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/flora-and-fauna-identification-guides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Books and DVDs","item":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/"},{"@type":"ListItem","position":3,"name":"Books","item":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/"},{"@type":"ListItem","position":4,"name":"Adults","item":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/"},{"@type":"ListItem","position":5,"name":"Books: Marine biology","item":"https:\/\/libreriadelmare.it\/en\/categoria-prodotto\/books-and-dvds\/books\/adults-books\/books-marine-biology\/"},{"@type":"ListItem","position":6,"name":"Flora and fauna identification guides"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]}},"image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat\/2620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat\/2599"}],"wp:post_type":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product?product_cat=2620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}