{"id":98142,"date":"2022-09-03T13:10:30","date_gmt":"2022-09-03T11:10:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/"},"modified":"2026-05-09T00:56:12","modified_gmt":"2026-05-08T22:56:12","slug":"arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/","title":{"rendered":"arcobaleno &#8211; 30 anni arcobaleno"},"content":{"rendered":"<p><strong>Arcobaleno <\/strong>&egrave; il <strong>pesce pi&ugrave; bello<\/strong> di tutti i mari. Lo chiamano cos&igrave; perch&eacute; <strong>le sue squame brillano di tutti i colori dell&rsquo;arcobaleno<\/strong>. Ma, ahim&egrave;, &egrave; cos&igrave; <strong>fiero e vanitoso<\/strong> che <strong>tutti lo evitano<\/strong> e lui <strong>si sente molto solo<\/strong>.<\/p>\n<p>Un giorno, per&ograve;, <strong>regala <\/strong>a un pesciolino <strong>una delle sue belle squame<\/strong>. Poi ne regala un&rsquo;altra, poi un&rsquo;altra e un&rsquo;altra ancora&#8230; e cos&igrave; scopre che, quando si divide quel che si ha con gli altri, si diventa felici.<\/p>\n<p>Et&agrave;: 4+<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il pesciolino pi\u00f9 bello di tutti i mari<\/p>\n<p class=\"autore\"><span>Author: <\/span>marcus pfister<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nord-sud edizioni (adriano salani editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788893083027<\/p>\n","protected":false},"featured_media":83978,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2614],"product_tag":[],"class_list":{"0":"post-98142","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-illustrated-books-and-fiction","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>arcobaleno - 30 anni arcobaleno - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"arcobaleno - 30 anni arcobaleno\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il pesciolino pi\u00f9 bello di tutti i mariAuthor: marcus pfisterPublisher: nord-sud edizioni (adriano salani editore)ISBN: 9788893083027\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"536\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/\",\"name\":\"arcobaleno - 30 anni arcobaleno - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arcobaleno-30-anni-pfister-3.jpg\",\"datePublished\":\"2022-09-03T11:10:30+00:00\",\"dateModified\":\"2026-05-08T22:56:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arcobaleno-30-anni-pfister-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arcobaleno-30-anni-pfister-3.jpg\",\"width\":536,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"arcobaleno &#8211; 30 anni arcobaleno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788893083027\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"arcobaleno - 30 anni arcobaleno - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/","og_locale":"en_US","og_type":"article","og_title":"arcobaleno - 30 anni arcobaleno","og_description":"Subtitle: il pesciolino pi\u00f9 bello di tutti i mariAuthor: marcus pfisterPublisher: nord-sud edizioni (adriano salani editore)ISBN: 9788893083027","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:56:12+00:00","og_image":[{"width":536,"height":711,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/","name":"arcobaleno - 30 anni arcobaleno - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3.jpg","datePublished":"2022-09-03T11:10:30+00:00","dateModified":"2026-05-08T22:56:12+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3.jpg","width":536,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/arcobaleno-30-anni-arcobaleno-marcus-pfister-9788893083027\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"arcobaleno &#8211; 30 anni arcobaleno"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788893083027","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arcobaleno-30-anni-pfister-3-226x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/98142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=98142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/83978"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=98142"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=98142"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=98142"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=98142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}