{"id":98096,"date":"2022-10-10T16:36:22","date_gmt":"2022-10-10T14:36:22","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/"},"modified":"2026-07-11T01:23:45","modified_gmt":"2026-07-10T23:23:45","slug":"gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/","title":{"rendered":"gatti marinai e polpi indovini"},"content":{"rendered":"<div class=\"dettaglioDati\">\n<p class=\"lh22 fs14\"><strong>Storie avventurose, sorprendenti, a volte drammatiche <\/strong>che servono a capire quanto incredibili e sottovalutate siano <strong>le capacit&agrave;, l&#8217;intelligenza, la socialit&agrave; di tanti animali<\/strong> con cui condividiamo la nostra esistenza sulla terra. <strong>Paul il polpo<\/strong> prevedeva i risultati delle partite dei mondiali di calcio; Hachik? il cane incarn&ograve; il simbolo della fedelt&agrave; al padrone; Jumbo l&#8217;elefante era il protagonista indiscusso del circo Barnum; <strong>Keiko l&#8217;orca<\/strong> divenne una celebrit&agrave; internazionale dopo aver recitato nel film per famiglie Free Willy. Dal racconto di queste e tante altre vicende, <strong>emerge come gli animali siano stati spesso protagonisti della storia, della societ&agrave; e dello spettacolo<\/strong> del mondo degli uomini. Un libro, quello di Lucifredi, per comprenderli meglio e imparare a rispettarli di pi&ugrave;.<\/p>\n<p class=\"lh22 fs14\">Edizione: 2022<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>insolite storie di animali famosi<\/p>\n<p class=\"autore\"><span>Author: <\/span>alfonso lucifredi<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ulrico Hoepli Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836011292<\/p>\n","protected":false},"featured_media":156151,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2815,2997,2811],"product_tag":[],"class_list":{"0":"post-98096","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anthologies-and-letters","7":"product_cat-narrative-narrative-and-essays","8":"product_cat-short-stories","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>gatti marinai e polpi indovini - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gatti marinai e polpi indovini\" \/>\n<meta property=\"og:description\" content=\"Subtitle: insolite storie di animali famosiAuthor: alfonso lucifrediPublisher: Ulrico Hoepli EditoreISBN: 9788836011292\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:23:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/\",\"name\":\"gatti marinai e polpi indovini - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg\",\"datePublished\":\"2022-10-10T14:36:22+00:00\",\"dateModified\":\"2026-07-10T23:23:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg\",\"width\":500,\"height\":783},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"gatti marinai e polpi indovini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836011292\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"gatti marinai e polpi indovini - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/","og_locale":"en_US","og_type":"article","og_title":"gatti marinai e polpi indovini","og_description":"Subtitle: insolite storie di animali famosiAuthor: alfonso lucifrediPublisher: Ulrico Hoepli EditoreISBN: 9788836011292","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:23:45+00:00","og_image":[{"width":500,"height":783,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/","name":"gatti marinai e polpi indovini - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg","datePublished":"2022-10-10T14:36:22+00:00","dateModified":"2026-07-10T23:23:45+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli.jpg","width":500,"height":783},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-9788836011292\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"gatti marinai e polpi indovini"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788836011292","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gatti-marinai-e-polpi-indovini-alfonso-lucifredi-hoepli-192x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/98096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=98096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/156151"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=98096"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=98096"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=98096"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=98096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}