{"id":98072,"date":"2022-10-25T12:18:08","date_gmt":"2022-10-25T10:18:08","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/"},"modified":"2026-07-11T01:22:57","modified_gmt":"2026-07-10T23:22:57","slug":"piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/","title":{"rendered":"piccolo manuale per cercatori di nuvole"},"content":{"rendered":"<p><strong>Osservare le nuvole in giro per i cieli di tutto il mondo<\/strong> &egrave; un&rsquo;avventura entusiasmante: le nuvole cambiano aspetto, hanno nomi diversi, assumono le forme pi&ugrave; strane, accompagnandoci ovunque andiamo o speriamo di arrivare.<\/p>\n<p>Per orientarsi nelle sterminate geografie celesti, per&ograve;, <strong>una guida risulta indispensabile<\/strong>: ed &egrave; per questo motivo che <strong>Vincenzo Levizzani, fisico italiano tra i maggiori esperti di nefologia<\/strong>, ha deciso di realizzare il <em>Piccolo manuale per cercatori di nuvole<\/em>&nbsp;e svelarci i segreti della vita delle nubi, terrestri ed extraterrestri, dalle quote pi&ugrave; alte a quelle pi&ugrave; basse, e le loro trasformazioni in piogge, temporali, nebbie.<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>vincenzo levizzani<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>il saggiatore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842831846<\/p>\n","protected":false},"featured_media":67677,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2580],"product_tag":[],"class_list":{"0":"post-98072","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-meteorological-navigation-and-meteorology","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>piccolo manuale per cercatori di nuvole - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"piccolo manuale per cercatori di nuvole\" \/>\n<meta property=\"og:description\" content=\"Author: vincenzo levizzaniPublisher: il saggiatoreISBN: 9788842831846\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/\",\"name\":\"piccolo manuale per cercatori di nuvole - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg\",\"datePublished\":\"2022-10-25T10:18:08+00:00\",\"dateModified\":\"2026-07-10T23:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg\",\"width\":500,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"piccolo manuale per cercatori di nuvole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842831846\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"piccolo manuale per cercatori di nuvole - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/","og_locale":"en_US","og_type":"article","og_title":"piccolo manuale per cercatori di nuvole","og_description":"Author: vincenzo levizzaniPublisher: il saggiatoreISBN: 9788842831846","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:22:57+00:00","og_image":[{"width":500,"height":703,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/","name":"piccolo manuale per cercatori di nuvole - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg","datePublished":"2022-10-25T10:18:08+00:00","dateModified":"2026-07-10T23:22:57+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani.jpg","width":500,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/piccolo-manuale-per-cercatori-di-nuvole-vincenzo-levizzani-9788842831846\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"piccolo manuale per cercatori di nuvole"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788842831846","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piccolo-manuale-per-cercatori-di-nuvole-levizzani-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/98072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=98072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/67677"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=98072"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=98072"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=98072"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=98072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}