{"id":97990,"date":"2022-12-04T16:50:27","date_gmt":"2022-12-04T15:50:27","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/"},"modified":"2026-05-09T00:52:51","modified_gmt":"2026-05-08T22:52:51","slug":"tela-intelaiata-la-jument-jean-guichard-3jg167880tela","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/","title":{"rendered":"tela intelaiata &#8220;la jument&#8221;"},"content":{"rendered":"<p>Stampata a pigmenti su tela Fine Art 360 gr\/mq di qualit&agrave; professionale viene successivamente&nbsp;intelaiata con cura su telai in legno massello di spessore 4 cm. in modo da creare un quadro finito Made in Italy dal look decisamente contemporaneo e&nbsp;gi&agrave; pronto per essere appeso.<\/p>\n<p>La stampa riflette sui bordi la parte esterna dell&rsquo;immagine, per donare un elegante effetto di continuit&agrave; che rifinisce con gusto ogni lato del quadro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 60&#215;80<\/p>\n<p class=\"autore\"><span>Author: <\/span>jean guichard<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>selected artworks<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>3JG167880TELA<\/p>\n","protected":false},"featured_media":148384,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2437],"product_tag":[],"class_list":{"0":"post-97990","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-photographs","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tela intelaiata &quot;la jument&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tela intelaiata &quot;la jument&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 60x80Author: jean guichardManufacturer: selected artworksISBN: 3JG167880TELA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:52:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"338\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;157,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/\",\"name\":\"tela intelaiata \\\"la jument\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jument-60x80-3jg1678-tela-20250506-101849.jpg\",\"datePublished\":\"2022-12-04T15:50:27+00:00\",\"dateModified\":\"2026-05-08T22:52:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jument-60x80-3jg1678-tela-20250506-101849.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jument-60x80-3jg1678-tela-20250506-101849.jpg\",\"width\":338,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tela intelaiata &#8220;la jument&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"157.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"3JG167880TELA\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tela intelaiata \"la jument\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/","og_locale":"en_US","og_type":"article","og_title":"tela intelaiata \"la jument\"","og_description":"Subtitle: cm 60x80Author: jean guichardManufacturer: selected artworksISBN: 3JG167880TELA","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:52:51+00:00","og_image":[{"width":338,"height":450,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;157,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/","name":"tela intelaiata \"la jument\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849.jpg","datePublished":"2022-12-04T15:50:27+00:00","dateModified":"2026-05-08T22:52:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849.jpg","width":338,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tela-intelaiata-la-jument-jean-guichard-3jg167880tela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tela intelaiata &#8220;la jument&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"157.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"3JG167880TELA","product_condition":"new"},"df_price":157,"df_sale_price":"","df_regular_price":157,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jument-60x80-3jg1678-tela-20250506-101849-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/148384"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97990"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97990"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97990"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}