{"id":97950,"date":"2022-12-20T13:25:59","date_gmt":"2022-12-20T12:25:59","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/"},"modified":"2026-07-11T01:18:59","modified_gmt":"2026-07-10T23:18:59","slug":"scafi-classici-a-vela-cristiano-bettini-9788846763525","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/","title":{"rendered":"scafi classici a vela"},"content":{"rendered":"<p><span class=\"s1\">L<\/span>e <strong>forme degli scafi d&rsquo;altura a vela<\/strong> si sono evolute per ottenere il <strong>miglior equilibrio dinamico e tenuta al mare a tutte le andature<\/strong>: sono queste le qualit&agrave; principali e pi&ugrave; ricercate e l&rsquo;indicatore della qualit&agrave; complessiva del progetto, ancor prima della pura velocit&agrave;. Tutti i compromessi ricercati nello sviluppo del&nbsp;<em>design<\/em>, anche quando condizionati dai&nbsp;<em>Regolamenti di stazza<\/em>&nbsp;per le regate, sono volti ad ottenere un compendio armonioso di caratteristiche efficaci, che si integrano proprio nelle forme. Il <strong>segreto dell&rsquo;equilibrio e del moto<\/strong> di un&rsquo;imbarcazione a vela risiede nella <strong>continua interazione e nella simmetria tra le superfici immerse nell&rsquo;acqua e nell&rsquo;aria<\/strong>, ma sul piano velico si pu&ograve; intervenire anche successivamente alla costruzione, sullo scafo molto poco; ecco perch&eacute; per esso sono richieste scelte pi&ugrave; vincolanti prima. Solo guardando dentro la confluenza di forme e caratteristiche che identificano ogni scafo a vela adatto alla navigazione d&rsquo;altura, potremo prevederne il comportamento in mare, comprendendo quali logiche e quali scelte siano all&rsquo;origine di ciascun progetto, che mira a rispondere a precisi requisiti di idrodinamicit&agrave;, bilanciamento, abitabilit&agrave;, governabilit&agrave; e velocit&agrave;, perfezionati in molti decenni di&nbsp;<em>design<\/em>&nbsp;e prove.<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il design per chi naviga. evoluzione, bilanciamento, qualit\u00e0 marine<\/p>\n<p class=\"autore\"><span>Author: <\/span>cristiano bettini<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni ets<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788846763525<\/p>\n","protected":false},"featured_media":105171,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2788],"product_tag":[],"class_list":{"0":"post-97950","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tiger-shark","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>scafi classici a vela - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"scafi classici a vela\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il design per chi naviga. evoluzione, bilanciamento, qualit\u00e0 marineAuthor: cristiano bettiniPublisher: edizioni etsISBN: 9788846763525\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;40,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/\",\"name\":\"scafi classici a vela - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/scafi-classici-a-vela-bettini-2.jpg\",\"datePublished\":\"2022-12-20T12:25:59+00:00\",\"dateModified\":\"2026-07-10T23:18:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/scafi-classici-a-vela-bettini-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/scafi-classici-a-vela-bettini-2.jpg\",\"width\":506,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/scafi-classici-a-vela-cristiano-bettini-9788846763525\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"scafi classici a vela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"40.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788846763525\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"scafi classici a vela - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/","og_locale":"en_US","og_type":"article","og_title":"scafi classici a vela","og_description":"Subtitle: il design per chi naviga. evoluzione, bilanciamento, qualit\u00e0 marineAuthor: cristiano bettiniPublisher: edizioni etsISBN: 9788846763525","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:18:59+00:00","og_image":[{"width":506,"height":720,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;40,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/","name":"scafi classici a vela - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2.jpg","datePublished":"2022-12-20T12:25:59+00:00","dateModified":"2026-07-10T23:18:59+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2.jpg","width":506,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/scafi-classici-a-vela-cristiano-bettini-9788846763525\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"scafi classici a vela"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"40.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788846763525","product_condition":"new"},"df_price":40,"df_sale_price":"","df_regular_price":40,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/scafi-classici-a-vela-bettini-2-211x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/105171"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}