{"id":97893,"date":"2023-01-31T12:58:02","date_gmt":"2023-01-31T11:58:02","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/"},"modified":"2026-05-09T00:51:09","modified_gmt":"2026-05-08T22:51:09","slug":"biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/","title":{"rendered":"biglietto con busta zoodicarta &#8220;pinguino&#8221;"},"content":{"rendered":"<p>Biglietto che riproduce un disegno originale di&nbsp;<em>Guja Ajolfi<\/em>.<\/p>\n<p><strong>Zoodicarta<\/strong>&nbsp;nasce per dar vita a un universo di animali disegnati, spesso dipinti, che popolano collezioni a tiratura limitata di quaderni, biglietti, cartoline e segnalibri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 7,5&#215;11<\/p>\n<p class=\"autore\"><span>Author: <\/span>guja ajolfi<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Zoodicarta<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1675166280<\/p>\n","protected":false},"featured_media":72306,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2653],"product_tag":[],"class_list":{"0":"post-97893","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-greeting-cards-and-postcards","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>biglietto con busta zoodicarta &quot;pinguino&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"biglietto con busta zoodicarta &quot;pinguino&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 7,5x11Author: guja ajolfiManufacturer: ZoodicartaISBN: LDM1675166280\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:51:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"527\" \/>\n\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;4,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/\",\"name\":\"biglietto con busta zoodicarta \\\"pinguino\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg\",\"datePublished\":\"2023-01-31T11:58:02+00:00\",\"dateModified\":\"2026-05-08T22:51:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg\",\"width\":527,\"height\":758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"biglietto con busta zoodicarta &#8220;pinguino&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"4.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1675166280\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"biglietto con busta zoodicarta \"pinguino\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/","og_locale":"en_US","og_type":"article","og_title":"biglietto con busta zoodicarta \"pinguino\"","og_description":"Subtitle: cm 7,5x11Author: guja ajolfiManufacturer: ZoodicartaISBN: LDM1675166280","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:51:09+00:00","og_image":[{"width":527,"height":758,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;4,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/","name":"biglietto con busta zoodicarta \"pinguino\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg","datePublished":"2023-01-31T11:58:02+00:00","dateModified":"2026-05-08T22:51:09+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi.jpg","width":527,"height":758},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-con-busta-zoodicarta-pinguino-guja-ajolfi-ldm1675166280\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"biglietto con busta zoodicarta &#8220;pinguino&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"4.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1675166280","product_condition":"new"},"df_price":4,"df_sale_price":"","df_regular_price":4,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-con-busta-zoodicarta-pinguino-ajolfi-209x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/72306"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}