{"id":97851,"date":"2023-02-25T16:12:26","date_gmt":"2023-02-25T15:12:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/porto-di-arenzano-n-909-10-1969-idro90910mod\/"},"modified":"2026-05-09T00:50:24","modified_gmt":"2026-05-08T22:50:24","slug":"porto-di-arenzano-n-909-10-1969-idro90910mod","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/","title":{"rendered":"porto di arenzano n. 909\/10 (1969)"},"content":{"rendered":"<p>Carta nautica dell&rsquo;Istituto Idrografico della Marina Italiana edita nel 1967. L&rsquo;esemplare a nostra disposizione &egrave; stato ristampato e aggiornato nel 1969.<\/p>\n<p>Sul retro: elementi tecnici della carta, avvertenza, foto in bianco e nero e aggiornamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 40&#215;48,5<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDRO90910MOD<\/p>\n","protected":false},"featured_media":74812,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-97851","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>porto di arenzano n. 909\/10 (1969) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"porto di arenzano n. 909\/10 (1969)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 40x48,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO90910MOD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:50:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1102\" \/>\n\t<meta property=\"og:image:height\" content=\"1328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;40,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/\",\"name\":\"porto di arenzano n. 909\\\/10 (1969) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/porto-di-arenzano-909-10-fronte.jpg\",\"datePublished\":\"2023-02-25T15:12:26+00:00\",\"dateModified\":\"2026-05-08T22:50:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/porto-di-arenzano-909-10-fronte.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/porto-di-arenzano-909-10-fronte.jpg\",\"width\":1102,\"height\":1328},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/porto-di-arenzano-n-909-10-1969-idro90910mod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"porto di arenzano n. 909\\\/10 (1969)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"40.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDRO90910MOD\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"porto di arenzano n. 909\/10 (1969) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/","og_locale":"en_US","og_type":"article","og_title":"porto di arenzano n. 909\/10 (1969)","og_description":"Subtitle: cm 40x48,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO90910MOD","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:50:24+00:00","og_image":[{"width":1102,"height":1328,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;40,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/","name":"porto di arenzano n. 909\/10 (1969) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte.jpg","datePublished":"2023-02-25T15:12:26+00:00","dateModified":"2026-05-08T22:50:24+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte.jpg","width":1102,"height":1328},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/porto-di-arenzano-n-909-10-1969-idro90910mod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"porto di arenzano n. 909\/10 (1969)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"40.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"IDRO90910MOD","product_condition":"new"},"df_price":40,"df_sale_price":"","df_regular_price":40,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/porto-di-arenzano-909-10-fronte-249x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/74812"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97851"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97851"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97851"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}