{"id":97836,"date":"2023-02-28T15:03:01","date_gmt":"2023-02-28T14:03:01","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/"},"modified":"2026-05-09T00:50:05","modified_gmt":"2026-05-08T22:50:05","slug":"dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/","title":{"rendered":"dall&#8217;isola s. pietro a c.\u00b0 san marco n. 47 (1979)"},"content":{"rendered":"<p>Carta nautica dell&rsquo;Istituto Idrografico della Marina Italiana edita nel 1974. L&rsquo;esemplare a nostra disposizione &egrave; stato ristampato e aggiornato nel 1979.<\/p>\n<p>Firma a penna.<\/p>\n<p>Margine sinistro superiore e inferioreseriamente compromesso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 75&#215;113,5<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDRO47MOD<\/p>\n","protected":false},"featured_media":75260,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-97836","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dall&#039;isola s. pietro a c.\u00b0 san marco n. 47 (1979) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dall&#039;isola s. pietro a c.\u00b0 san marco n. 47 (1979)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 75x113,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO47MOD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"843\" \/>\n\t<meta property=\"og:image:height\" content=\"1247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;100,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/\",\"name\":\"dall'isola s. pietro a c.\u00b0 san marco n. 47 (1979) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg\",\"datePublished\":\"2023-02-28T14:03:01+00:00\",\"dateModified\":\"2026-05-08T22:50:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg\",\"width\":843,\"height\":1247},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dall&#8217;isola s. pietro a c.\u00b0 san marco n. 47 (1979)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"100.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDRO47MOD\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dall'isola s. pietro a c.\u00b0 san marco n. 47 (1979) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/","og_locale":"en_US","og_type":"article","og_title":"dall'isola s. pietro a c.\u00b0 san marco n. 47 (1979)","og_description":"Subtitle: cm 75x113,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO47MOD","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:50:05+00:00","og_image":[{"width":843,"height":1247,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;100,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/","name":"dall'isola s. pietro a c.\u00b0 san marco n. 47 (1979) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg","datePublished":"2023-02-28T14:03:01+00:00","dateModified":"2026-05-08T22:50:05+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-rotated.jpg","width":843,"height":1247},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dall-isola-s-pietro-a-c-san-marco-n-47-1979-idro47mod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dall&#8217;isola s. pietro a c.\u00b0 san marco n. 47 (1979)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"100.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"IDRO47MOD","product_condition":"new"},"df_price":100,"df_sale_price":"","df_regular_price":100,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dall-isola-s-pietro-a-c-san-marco-47-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/75260"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97836"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97836"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97836"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}