{"id":97800,"date":"2023-03-02T17:11:20","date_gmt":"2023-03-02T16:11:20","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/"},"modified":"2026-05-09T00:49:31","modified_gmt":"2026-05-08T22:49:31","slug":"dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/","title":{"rendered":"dal golfo del leone alle isole eolie n. l(c) 432 (1978)"},"content":{"rendered":"<p>Carta nautica dell&rsquo;Istituto Idrografico della Marina Italiana edita nel 1965. L&rsquo;esemplare a nostra disposizione &egrave; stato ristampato e aggiornato nel 1978.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 113,5&#215;74,5<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDROLC432MOD<\/p>\n","protected":false},"featured_media":75723,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-97800","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dal golfo del leone alle isole eolie n. l(c) 432 (1978) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dal golfo del leone alle isole eolie n. l(c) 432 (1978)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 113,5x74,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDROLC432MOD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1213\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;160,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/\",\"name\":\"dal golfo del leone alle isole eolie n. l(c) 432 (1978) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg\",\"datePublished\":\"2023-03-02T16:11:20+00:00\",\"dateModified\":\"2026-05-08T22:49:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg\",\"width\":1213,\"height\":806},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dal golfo del leone alle isole eolie n. l(c) 432 (1978)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"160.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDROLC432MOD\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dal golfo del leone alle isole eolie n. l(c) 432 (1978) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/","og_locale":"en_US","og_type":"article","og_title":"dal golfo del leone alle isole eolie n. l(c) 432 (1978)","og_description":"Subtitle: cm 113,5x74,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDROLC432MOD","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:49:31+00:00","og_image":[{"width":1213,"height":806,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;160,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/","name":"dal golfo del leone alle isole eolie n. l(c) 432 (1978) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg","datePublished":"2023-03-02T16:11:20+00:00","dateModified":"2026-05-08T22:49:31+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432.jpg","width":1213,"height":806},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-1978-idrolc432mod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dal golfo del leone alle isole eolie n. l(c) 432 (1978)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"160.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"IDROLC432MOD","product_condition":"new"},"df_price":160,"df_sale_price":"","df_regular_price":160,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-golfo-del-leone-alle-isole-eolie-n-l-c-432-300x199.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/75723"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97800"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97800"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97800"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}