{"id":97786,"date":"2023-03-03T17:32:46","date_gmt":"2023-03-03T16:32:46","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/"},"modified":"2026-05-09T00:49:15","modified_gmt":"2026-05-08T22:49:15","slug":"dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/","title":{"rendered":"dal gombo al canale di piombino  e isole elba &#8211; capraia &#8211; gorgona n. 4 (1960)"},"content":{"rendered":"<p>Carta nautica dell&rsquo;Istituto Idrografico della Marina Italiana edita nel 1957. L&rsquo;esemplare a nostra disposizione &egrave; stato ristampato e aggiornato nel 1960.<\/p>\n<p>Piccole macchie sparse.<\/p>\n<p>Annotazioni sparse a matita.<\/p>\n<p>Piegature evidenti.<\/p>\n<p>Il bordo della carta &egrave; stato rinforzato con nastro adesivo coevo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 113&#215;74,5<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>istituto idrografico della marina (IIM)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>IDRO4MOD<\/p>\n","protected":false},"featured_media":137145,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461],"product_tag":[],"class_list":{"0":"post-97786","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_shipping_class-packaging","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 113x74,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO4MOD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"897\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;130,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/\",\"name\":\"dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-gombo-al-canale-di-piombino-n-4-2.jpg\",\"datePublished\":\"2023-03-03T16:32:46+00:00\",\"dateModified\":\"2026-05-08T22:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-gombo-al-canale-di-piombino-n-4-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dal-gombo-al-canale-di-piombino-n-4-2.jpg\",\"width\":897,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dal gombo al canale di piombino e isole elba &#8211; capraia &#8211; gorgona n. 4 (1960)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"130.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"IDRO4MOD\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/","og_locale":"en_US","og_type":"article","og_title":"dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960)","og_description":"Subtitle: cm 113x74,5Manufacturer: istituto idrografico della marina (IIM)ISBN: IDRO4MOD","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:49:15+00:00","og_image":[{"width":897,"height":1300,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;130,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/","name":"dal gombo al canale di piombino e isole elba - capraia - gorgona n. 4 (1960) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2.jpg","datePublished":"2023-03-03T16:32:46+00:00","dateModified":"2026-05-08T22:49:15+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2.jpg","width":897,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dal-gombo-al-canale-di-piombino-e-isole-elba-capraia-gorgona-n-4-1960-idro4mod\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dal gombo al canale di piombino e isole elba &#8211; capraia &#8211; gorgona n. 4 (1960)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"130.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"IDRO4MOD","product_condition":"new"},"df_price":130,"df_sale_price":"","df_regular_price":130,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dal-gombo-al-canale-di-piombino-n-4-2-207x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/137145"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97786"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97786"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}