{"id":97486,"date":"2023-06-14T13:06:34","date_gmt":"2023-06-14T11:06:34","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/inland-01-faroe-islands-aa-vv-ldm1686740792\/"},"modified":"2026-07-11T01:07:23","modified_gmt":"2026-07-10T23:07:23","slug":"inland-01-faroe-islands-aa-vv-ldm1686740792","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/","title":{"rendered":"inland 01 &#8211; faroe islands"},"content":{"rendered":"<p>Born by the imminent desire to unveil the true world no tourist has ever seen, <em>Inland<\/em> is <strong>a new magazine aiming to explore the culture of some of the Earth&rsquo;s most hidden and isolated countries above the stereotypical level<\/strong>. It&rsquo;s an invitation for you <strong>to join a travel experience under the superficial and chatted world<\/strong>. Through a documentary narrative between <strong>photography and design<\/strong>, it intends to give visibility to different experiences of individuals in countries otherwise often perceived as homogenous, hereby opening deeper perspectives of these unknown places and the people behind them.<\/p>\n<p>Edition: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>inland magazine<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1686740792<\/p>\n","protected":false},"featured_media":91113,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2593,2634],"product_tag":[],"class_list":{"0":"post-97486","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magazines","7":"product_cat-world-tourist-guides","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>inland 01 - faroe islands - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"inland 01 - faroe islands\" \/>\n<meta property=\"og:description\" content=\"Author: aa.vv.Publisher: inland magazineISBN: LDM1686740792\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;30,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/\",\"name\":\"inland 01 - faroe islands - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/inland-01-faroe-islands-2023-1.jpg\",\"datePublished\":\"2023-06-14T11:06:34+00:00\",\"dateModified\":\"2026-07-10T23:07:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/inland-01-faroe-islands-2023-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/inland-01-faroe-islands-2023-1.jpg\",\"width\":531,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/inland-01-faroe-islands-aa-vv-ldm1686740792\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"inland 01 &#8211; faroe islands\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1686740792\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"inland 01 - faroe islands - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/","og_locale":"en_US","og_type":"article","og_title":"inland 01 - faroe islands","og_description":"Author: aa.vv.Publisher: inland magazineISBN: LDM1686740792","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:07:23+00:00","og_image":[{"width":531,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;30,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/","name":"inland 01 - faroe islands - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1.jpg","datePublished":"2023-06-14T11:06:34+00:00","dateModified":"2026-07-10T23:07:23+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1.jpg","width":531,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/inland-01-faroe-islands-aa-vv-ldm1686740792\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"inland 01 &#8211; faroe islands"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1686740792","product_condition":"new"},"df_price":30,"df_sale_price":"","df_regular_price":30,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/inland-01-faroe-islands-2023-1-228x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/97486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=97486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/91113"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=97486"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=97486"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=97486"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=97486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}