{"id":96942,"date":"2019-04-30T16:00:24","date_gmt":"2019-04-30T14:00:24","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/"},"modified":"2026-07-11T02:20:46","modified_gmt":"2026-07-11T00:20:46","slug":"l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/","title":{"rendered":"l&#8217;istinto del gatto mediterraneo"},"content":{"rendered":"<p>I gatti sono delle isole, mondi a parte, misteriosi e segreti, nel quale agli umani &egrave; concesso di entrare solo in punta di piedi. Lo sa bene Paolo Ganz che, armato di penna e del suo inseparabile taccuino, ha camminato lungo coste e porti remoti del Mediterraneo, parlando con lo sguardo ai felini che da sempre li abitano. E i gatti, capaci di custodire nel silenzio segreti vecchi e nuovi, camminano con lui, avvinti da invisibili tracce olfattive che solo le loro narici sanno seguire e decodificare.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>piccolo elogio dell&#8217;isolagatto e dei felini di mare<\/p>\n<p class=\"autore\"><span>Author: <\/span>ganz p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ediciclo Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865492994<\/p>\n","protected":false},"featured_media":126010,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2983,2811],"product_tag":[],"class_list":{"0":"post-96942","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-literary-essays","7":"product_cat-short-stories","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;istinto del gatto mediterraneo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;istinto del gatto mediterraneo\" \/>\n<meta property=\"og:description\" content=\"Subtitle: piccolo elogio dell&#039;isolagatto e dei felini di mareAuthor: ganz p.Publisher: Ediciclo EditoreISBN: 9788865492994\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:20:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"385\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/\",\"name\":\"l'istinto del gatto mediterraneo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg\",\"datePublished\":\"2019-04-30T14:00:24+00:00\",\"dateModified\":\"2026-07-11T00:20:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg\",\"width\":385,\"height\":583},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;istinto del gatto mediterraneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865492994\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'istinto del gatto mediterraneo - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/","og_locale":"en_US","og_type":"article","og_title":"l'istinto del gatto mediterraneo","og_description":"Subtitle: piccolo elogio dell'isolagatto e dei felini di mareAuthor: ganz p.Publisher: Ediciclo EditoreISBN: 9788865492994","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:20:46+00:00","og_image":[{"width":385,"height":583,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/","name":"l'istinto del gatto mediterraneo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg","datePublished":"2019-04-30T14:00:24+00:00","dateModified":"2026-07-11T00:20:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2.jpg","width":385,"height":583},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-istinto-del-gatto-mediterraneo-ganz-p-9788865492994\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;istinto del gatto mediterraneo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788865492994","product_condition":"new"},"df_price":9.5,"df_sale_price":"","df_regular_price":9.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/istinto-gatto-mediterraneo-paolo-ganz-ediciclo-2-198x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/96942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=96942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/126010"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=96942"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=96942"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=96942"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=96942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}