{"id":96845,"date":"2019-06-18T13:52:11","date_gmt":"2019-06-18T11:52:11","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/aqua-formis-p-9788897123286\/"},"modified":"2026-05-09T01:33:06","modified_gmt":"2026-05-08T23:33:06","slug":"aqua-formis-p-9788897123286","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/","title":{"rendered":"aqua"},"content":{"rendered":"<p>Un libro dedicato all&#8217;acqua, fonte di vita, madre di tutte le creature del pianeta. Un viaggio attraverso le forme, i colori, le luci e i comportamenti delle creature d&rsquo;acqua. Dagli oceani ai mari tropicali, dal Mar Rosso fino al Mar Mediterraneo.<\/p>\n<p>L&rsquo;<strong>oscurit&agrave;<\/strong> e le sue creature misteriose.<\/p>\n<p>La <strong>luce<\/strong>, fonte di energia per l&rsquo;ecosistema e creatrice di spettacolari giochi. I colori, codici di comunicazione di un mondo complesso e meraviglioso.<\/p>\n<p>Le <strong>forme<\/strong>, forgiate dall&#8217;evoluzione, declinate in una variet&agrave; indescrivibile di soluzioni funzionali.<\/p>\n<p>Le <strong>maschere<\/strong> antropomorfe di esseri apparentemente mostruosi, ma incredibilmente affascinanti.<\/p>\n<p>La <strong>vita<\/strong> e la <strong>morte<\/strong>, strettamente legate: l&rsquo;investimento delle specie sul proprio futuro, anche attraverso il sacrificio dell&rsquo;individuo, in favore della collettivit&agrave;; le cure parentali di genitori determinati.<\/p>\n<p>La <strong>predazione<\/strong>, regola universale del mondo della natura, mangiare ed essere mangiati.<\/p>\n<p>La <strong>sopravvivenza<\/strong>, sopravvivere al predatore pi&ugrave; avido, cinico e determinato: l&rsquo;uomo. &Egrave; forse questa una missione impossibile?<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>misteri del mondo sommerso<\/p>\n<p class=\"autore\"><span>Author: <\/span>formis p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>daniele marson editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788897123286<\/p>\n","protected":false},"featured_media":134749,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2621],"product_tag":[],"class_list":{"0":"post-96845","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-picture-books","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>aqua - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aqua\" \/>\n<meta property=\"og:description\" content=\"Subtitle: misteri del mondo sommersoAuthor: formis p.Publisher: daniele marson editoreISBN: 9788897123286\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"401\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;34,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/\",\"name\":\"aqua - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg\",\"datePublished\":\"2019-06-18T11:52:11+00:00\",\"dateModified\":\"2026-05-08T23:33:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg\",\"width\":401,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/aqua-formis-p-9788897123286\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"aqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"34.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788897123286\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"aqua - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/","og_locale":"en_US","og_type":"article","og_title":"aqua","og_description":"Subtitle: misteri del mondo sommersoAuthor: formis p.Publisher: daniele marson editoreISBN: 9788897123286","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:33:06+00:00","og_image":[{"width":401,"height":600,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;34,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/","name":"aqua - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg","datePublished":"2019-06-18T11:52:11+00:00","dateModified":"2026-05-08T23:33:06+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2.jpg","width":401,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/aqua-formis-p-9788897123286\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"aqua"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"34.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788897123286","product_condition":"new"},"df_price":34,"df_sale_price":"","df_regular_price":34,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/aqua-misteri-mondo-sommerso-formis-marson-2-201x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/96845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=96845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/134749"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=96845"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=96845"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=96845"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=96845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}