{"id":96803,"date":"2019-07-10T16:04:18","date_gmt":"2019-07-10T14:04:18","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-mediterraneo-in-barca-simenon-g-9788845933936\/"},"modified":"2026-07-11T02:18:10","modified_gmt":"2026-07-11T00:18:10","slug":"il-mediterraneo-in-barca-simenon-g-9788845933936","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/","title":{"rendered":"il mediterraneo in barca"},"content":{"rendered":"<p>Che Simenon sia un prodigioso narratore &egrave; a tutti noto. Ma forse non tutti sanno che, in particolare fra il 1931 e il 1946, &egrave; stato un reporter non meno prodigioso e singolare. Singolare perch&eacute;, lungi dal considerarsi un inviato speciale, i suoi reportage li ha scritti <em>per s&eacute;<\/em>, per viaggiare, per finanziare la sua curiosit&agrave;. Quella curiosit&agrave; nei confronti dell&rsquo;uomo che ha scoperto in s&eacute; sin da quando, giovanissimo, lavorava alla &laquo;Gazette de Li&egrave;ge&raquo;: &laquo;Ho sempre colto la differenza fra l&rsquo;uomo vestito e l&rsquo;uomo nudo&raquo; ha dichiarato. &laquo;Intendo dire l&rsquo;uomo com&rsquo;&egrave; davvero e l&rsquo;uomo come si mostra in pubblico&#8230; e anche come si vede allo specchio&raquo;. Cos&igrave;, alla vigilia di ogni viaggio, Simenon andava da un amico caporedattore e gli diceva: &laquo;La settimana prossima parto. Le interessano dodici articoli?&raquo;. Ma proprio perch&eacute; concepiti in funzione dell&rsquo;unica attivit&agrave; che gli stesse a cuore, la scrittura (non a caso ha voluto intitolare il volume che li raccoglie <em>Mes apprentissages<\/em>, ossia &laquo;Il mio apprendistato&raquo;), i suoi pezzi giornalistici non fanno, dunque, che rivelarci un&rsquo;altra faccia del Simenon romanziere. Lo dimostra questo resoconto di una crociera compiuta nel Mediterraneo (da Porquerolles alla Tunisia, passando dall&#8217;Elba, Messina, Siracusa, Malta) a bordo di una goletta: una lunga crociera durante la quale Simenon, che si era ripromesso di capire e descrivere il Mare Nostrum, non potr&agrave; che confermarsi nella sua vera vocazione, la stessa di Stevenson: raccontare storie.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>simenon g.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Adelphi Edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788845933936<\/p>\n","protected":false},"featured_media":162550,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2961,2811,2965],"product_tag":[],"class_list":{"0":"post-96803","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-chronicles-logbooks-and-travel-reports","8":"product_cat-short-stories","9":"product_cat-short-stories-novels-and-articles","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il mediterraneo in barca - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il mediterraneo in barca\" \/>\n<meta property=\"og:description\" content=\"Author: simenon g.Publisher: Adelphi EdizioniISBN: 9788845933936\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:18:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"354\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/\",\"name\":\"il mediterraneo in barca - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg\",\"datePublished\":\"2019-07-10T14:04:18+00:00\",\"dateModified\":\"2026-07-11T00:18:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg\",\"width\":354,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-mediterraneo-in-barca-simenon-g-9788845933936\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il mediterraneo in barca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788845933936\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il mediterraneo in barca - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/","og_locale":"en_US","og_type":"article","og_title":"il mediterraneo in barca","og_description":"Author: simenon g.Publisher: Adelphi EdizioniISBN: 9788845933936","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:18:10+00:00","og_image":[{"width":354,"height":599,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/","name":"il mediterraneo in barca - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg","datePublished":"2019-07-10T14:04:18+00:00","dateModified":"2026-07-11T00:18:10+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi.jpg","width":354,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-mediterraneo-in-barca-simenon-g-9788845933936\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il mediterraneo in barca"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788845933936","product_condition":"new"},"df_price":17,"df_sale_price":"","df_regular_price":17,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/il-mediterraneo-in-barca-georges-simenon-adelphi-177x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/96803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=96803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/162550"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=96803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=96803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=96803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=96803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}