{"id":96686,"date":"2019-09-19T15:06:06","date_gmt":"2019-09-19T13:06:06","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-custodi-degli-abissi-spirito-p-9788865493045\/"},"modified":"2026-07-11T02:16:07","modified_gmt":"2026-07-11T00:16:07","slug":"i-custodi-degli-abissi-spirito-p-9788865493045","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/","title":{"rendered":"i custodi degli abissi"},"content":{"rendered":"<p>Il mare nasconde un&rsquo;infinita\u0300 di storie spesso dimenticate. Sul fondo del mare relitti di ogni epoca racchiudono come custodi degli abissi vicende la cui eco puo\u0300 arrivare fino ai nostri giorni. Scoprire ed esplorare queste testimonianze significa entrare in una dimensione dove il tempo riprende la sua corsa dopo un lungo oblio, creando vortici dove si mischiano impegno, passione, ossessione. Attraverso il racconto di alcune di queste esplorazioni, come la storia del Vascello Mercurio affondato nel 1812 o del Bombardiere Americano B-24 precipitato in mare durante la Seconda Guerra Mondiale, o del tesoro depredato dal Piroscafo Polluce, l&rsquo;autore riannoda i fili di memorie perdute che arrivano fino a noi e ci costringono a fare i conti con il presente.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>piccolo trattato sui naufragi del tempo<\/p>\n<p class=\"autore\"><span>Author: <\/span>spirito p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ediciclo Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865493045<\/p>\n","protected":false},"featured_media":134043,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2983,2589,2811,3086],"product_tag":[],"class_list":{"0":"post-96686","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-literary-essays","7":"product_cat-books-diving-literature","8":"product_cat-short-stories","9":"product_cat-shipwrecks","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i custodi degli abissi - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i custodi degli abissi\" \/>\n<meta property=\"og:description\" content=\"Subtitle: piccolo trattato sui naufragi del tempoAuthor: spirito p.Publisher: Ediciclo EditoreISBN: 9788865493045\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"396\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/\",\"name\":\"i custodi degli abissi - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg\",\"datePublished\":\"2019-09-19T13:06:06+00:00\",\"dateModified\":\"2026-07-11T00:16:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg\",\"width\":396,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-custodi-degli-abissi-spirito-p-9788865493045\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i custodi degli abissi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865493045\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i custodi degli abissi - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/","og_locale":"en_US","og_type":"article","og_title":"i custodi degli abissi","og_description":"Subtitle: piccolo trattato sui naufragi del tempoAuthor: spirito p.Publisher: Ediciclo EditoreISBN: 9788865493045","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:16:07+00:00","og_image":[{"width":396,"height":601,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/","name":"i custodi degli abissi - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg","datePublished":"2019-09-19T13:06:06+00:00","dateModified":"2026-07-11T00:16:07+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3.jpg","width":396,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-custodi-degli-abissi-spirito-p-9788865493045\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i custodi degli abissi"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788865493045","product_condition":"new"},"df_price":9.5,"df_sale_price":"","df_regular_price":9.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/custodi-degli-abissi-pietro-spirito-ediciclo-3-198x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/96686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=96686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/134043"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=96686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=96686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=96686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=96686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}