{"id":96561,"date":"2019-11-27T15:51:44","date_gmt":"2019-11-27T14:51:44","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/"},"modified":"2026-07-11T02:13:50","modified_gmt":"2026-07-11T00:13:50","slug":"l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/","title":{"rendered":"l&#8217;impiombatura delle cime moderne"},"content":{"rendered":"<p>Che l&#8217;impiombatura delle moderne cime intrecciate non sia un mistero occulto, bens&igrave; una tecnica artigianale facilmente apprendibile, lo dimostra questo testo riccamente illustrato dell&#8217;esperto di cime e impiombature Egmont M. Friedl.<\/p>\n<p>Con il suo aiuto e con l&#8217;ausilio degli attrezzi per impiombature qui presentati, otterrete passo dopo passo delle perfette impiombature a occhio, a occhio con redancia e impiombature corte o lunghe per unire due cime. Sono contemplate sia le cime convenzionali sia le cime con anima in Dyneema sia le altre cime in fibre ad altro modulo.<\/p>\n<p>Dopo questa lettura potrete facilmente destreggiarvi anche fra rigenerazioni di cime, sartiame, grilli morbidi, cime d&#8217;ormeggio e gerli.<\/p>\n<p>Diventerete cos&igrave; impiombatori esperti e potrete in futuro produrre le vostre scotte, cunningham e tesabase, drizze e cime per ormeggiare&#8230; Tutto ci&ograve; vi permetter&agrave; non solo di risparmiare, ma di dotare la vostra barca di una veste elegante e marinaresca.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>spiegata passo dopo passo<\/p>\n<p class=\"autore\"><span>Author: <\/span>friedl e.m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Nutrimenti Mare (Nutrimenti)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865947043<\/p>\n","protected":false},"featured_media":102351,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2751,2755],"product_tag":[],"class_list":{"0":"post-96561","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-knots","7":"product_cat-rigging-and-sails","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;impiombatura delle cime moderne - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;impiombatura delle cime moderne\" \/>\n<meta property=\"og:description\" content=\"Subtitle: spiegata passo dopo passoAuthor: friedl e.m.Publisher: Nutrimenti Mare (Nutrimenti)ISBN: 9788865947043\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"389\" \/>\n\t<meta property=\"og:image:height\" content=\"519\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/\",\"name\":\"l'impiombatura delle cime moderne - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg\",\"datePublished\":\"2019-11-27T14:51:44+00:00\",\"dateModified\":\"2026-07-11T00:13:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg\",\"width\":389,\"height\":519},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;impiombatura delle cime moderne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865947043\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'impiombatura delle cime moderne - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/","og_locale":"en_US","og_type":"article","og_title":"l'impiombatura delle cime moderne","og_description":"Subtitle: spiegata passo dopo passoAuthor: friedl e.m.Publisher: Nutrimenti Mare (Nutrimenti)ISBN: 9788865947043","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:13:50+00:00","og_image":[{"width":389,"height":519,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/","name":"l'impiombatura delle cime moderne - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg","datePublished":"2019-11-27T14:51:44+00:00","dateModified":"2026-07-11T00:13:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2.jpg","width":389,"height":519},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-impiombatura-delle-cime-moderne-friedl-e-m-9788865947043\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;impiombatura delle cime moderne"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788865947043","product_condition":"new"},"df_price":29,"df_sale_price":"","df_regular_price":29,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/impiombatura-delle-cime-moderne-friedl-nutrimenti-2-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/96561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=96561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/102351"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=96561"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=96561"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=96561"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=96561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}