{"id":95831,"date":"2021-01-29T12:08:51","date_gmt":"2021-01-29T11:08:51","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/"},"modified":"2026-05-09T01:18:30","modified_gmt":"2026-05-08T23:18:30","slug":"denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/","title":{"rendered":"denecia &#8211; approdi nella pandemia"},"content":{"rendered":"<p>Quello di Denecia e di Roberto Soldatini &egrave; un sodalizio davvero speciale, ancora di pi&ugrave; in una situazione di emergenza internazionale. Per la prima volta la pandemia causata dal Covid-19 viene raccontata in un libro da chi vive in barca, tra peripezie burocratiche e avventurose navigazioni, affrontate con il profondo legame dei due protagonisti.<\/p>\n<p>&Egrave; il racconto di approdi da sogno lungo pi&ugrave; di tremila miglia sotto la chiglia (seimila chilometri), tra Italia, Grecia, Albania, Montenegro, Croazia e Slovenia, in baie e porticcioli dove Denecia era quasi sempre l&rsquo;unica barca presente a causa del lockdown.<\/p>\n<p>&#8220;Fa arrabbiare questo libro che pone in discussione ogni nostra scelta&#8221;, come scrive nella postfazione Sergio Nazzaro. &#8220;Perch&eacute; prima della pandemia era un sognare ad occhi aperti, durante la pandemia sembra essere l&rsquo;unica forma possibile di sopravvivenza morale e ontologica: abitare il sogno.&#8221;<\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>roberto soldatini<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842563273<\/p>\n","protected":false},"featured_media":107029,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805],"product_tag":[],"class_list":{"0":"post-95831","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>denecia - approdi nella pandemia - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"denecia - approdi nella pandemia\" \/>\n<meta property=\"og:description\" content=\"Author: roberto soldatiniPublisher: Ugo Mursia EditoreISBN: 9788842563273\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:18:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/\",\"name\":\"denecia - approdi nella pandemia - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg\",\"datePublished\":\"2021-01-29T11:08:51+00:00\",\"dateModified\":\"2026-05-08T23:18:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg\",\"width\":500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"denecia &#8211; approdi nella pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842563273\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"denecia - approdi nella pandemia - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/","og_locale":"en_US","og_type":"article","og_title":"denecia - approdi nella pandemia","og_description":"Author: roberto soldatiniPublisher: Ugo Mursia EditoreISBN: 9788842563273","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:18:30+00:00","og_image":[{"width":500,"height":750,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/","name":"denecia - approdi nella pandemia - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg","datePublished":"2021-01-29T11:08:51+00:00","dateModified":"2026-05-08T23:18:30+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1.jpg","width":500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/denecia-approdi-nella-pandemia-roberto-soldatini-9788842563273\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"denecia &#8211; approdi nella pandemia"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788842563273","product_condition":"new"},"df_price":17,"df_sale_price":"","df_regular_price":17,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/denecia-approdi-nella-pandemia-roberto-soldatini-mursia-1-200x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/95831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=95831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/107029"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=95831"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=95831"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=95831"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=95831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}