{"id":95731,"date":"2021-03-31T17:05:00","date_gmt":"2021-03-31T15:05:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/"},"modified":"2026-07-11T01:54:52","modified_gmt":"2026-07-10T23:54:52","slug":"sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/","title":{"rendered":"sulle rotte di sebastiano"},"content":{"rendered":"<p>Raccontare il mare e la storia, l&#8217;intuizione geniale per valorizzare il patrimonio del passato.<\/p>\n<p>Dieci itinerari consigliati alla scoperta dei luoghi del cuore del padre dell&#8217;archeologia subacquea di Sicilia, l&#8217;archeologo e &#8220;Sovrintendente del mare&#8221; Sebastiano Tusa.<\/p>\n<p>L&#8217;archeologia subacquea &egrave; diventata, grazie a lui, una realt&agrave; concreta, un&#8217;offerta turistica che conta gi&agrave; numerosi itinerari a disposizione degli appassionati del mare che possono fruirne nel pieno rispetto dell&#8217;ambiente. Torniamo insieme sui suoi luoghi tra isole, coste, fondali ed entroterra, per capire meglio la storia del Mar Mediterraneo.<\/p>\n<p>Edizione: 2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>alla scoperta di una sicilia insolita tra terra e mare<\/p>\n<p class=\"autore\"><span>Author: <\/span>maria laura crescimanno<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>angelo mazzotta editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788888958637<\/p>\n","protected":false},"featured_media":142624,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3088,2587,3086],"product_tag":[],"class_list":{"0":"post-95731","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-anchors-and-amphorae","7":"product_cat-books-diving-dive-guides","8":"product_cat-shipwrecks","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sulle rotte di sebastiano - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sulle rotte di sebastiano\" \/>\n<meta property=\"og:description\" content=\"Subtitle: alla scoperta di una sicilia insolita tra terra e mareAuthor: maria laura crescimannoPublisher: angelo mazzotta editoreISBN: 9788888958637\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/\",\"name\":\"sulle rotte di sebastiano - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sulle-rotte-di-sebastiano-4.jpg\",\"datePublished\":\"2021-03-31T15:05:00+00:00\",\"dateModified\":\"2026-07-10T23:54:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sulle-rotte-di-sebastiano-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sulle-rotte-di-sebastiano-4.jpg\",\"width\":500,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sulle rotte di sebastiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788888958637\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sulle rotte di sebastiano - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/","og_locale":"en_US","og_type":"article","og_title":"sulle rotte di sebastiano","og_description":"Subtitle: alla scoperta di una sicilia insolita tra terra e mareAuthor: maria laura crescimannoPublisher: angelo mazzotta editoreISBN: 9788888958637","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:54:52+00:00","og_image":[{"width":500,"height":772,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/","name":"sulle rotte di sebastiano - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4.jpg","datePublished":"2021-03-31T15:05:00+00:00","dateModified":"2026-07-10T23:54:52+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4.jpg","width":500,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sulle-rotte-di-sebastiano-maria-laura-crescimanno-9788888958637\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sulle rotte di sebastiano"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788888958637","product_condition":"new"},"df_price":19.9,"df_sale_price":"","df_regular_price":19.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sulle-rotte-di-sebastiano-4-194x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/95731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=95731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142624"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=95731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=95731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=95731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=95731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}