{"id":95233,"date":"2019-02-03T19:58:17","date_gmt":"2019-02-03T18:58:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/"},"modified":"2026-07-11T02:47:47","modified_gmt":"2026-07-11T00:47:47","slug":"tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/","title":{"rendered":"tabellone didattico &#8220;quesiti di navigazione notturna e diurna&#8221;"},"content":{"rendered":"<p>Tabellone didattico in PVC opaco antiriflesso da 0,4 mm provvisto di due occhielli in metallo sul lato superiore per la messa in opera a parete.<\/p>\n<p>Da procurare su richiesta in 4 giorni lavorativi circa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 70&#215;100<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Edizioni il Frangente<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>TAB07<\/p>\n","protected":false},"featured_media":95234,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2651],"product_tag":[],"class_list":{"0":"post-95233","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stickers-cards-and-educational-posters","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tabellone didattico &quot;quesiti di navigazione notturna e diurna&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tabellone didattico &quot;quesiti di navigazione notturna e diurna&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 70x100Manufacturer: Edizioni il FrangenteISBN: TAB07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:47:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;31,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/\",\"name\":\"tabellone didattico \\\"quesiti di navigazione notturna e diurna\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tab07.jpg\",\"datePublished\":\"2019-02-03T18:58:17+00:00\",\"dateModified\":\"2026-07-11T00:47:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tab07.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tab07.jpg\",\"width\":424,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tabellone didattico &#8220;quesiti di navigazione notturna e diurna&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"31.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"TAB07\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tabellone didattico \"quesiti di navigazione notturna e diurna\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/","og_locale":"en_US","og_type":"article","og_title":"tabellone didattico \"quesiti di navigazione notturna e diurna\"","og_description":"Subtitle: cm 70x100Manufacturer: Edizioni il FrangenteISBN: TAB07","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:47:47+00:00","og_image":[{"width":424,"height":600,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;31,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/","name":"tabellone didattico \"quesiti di navigazione notturna e diurna\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07.jpg","datePublished":"2019-02-03T18:58:17+00:00","dateModified":"2026-07-11T00:47:47+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07.jpg","width":424,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tabellone-didattico-quesiti-di-navigazione-notturna-e-diurna-tab07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tabellone didattico &#8220;quesiti di navigazione notturna e diurna&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"31.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"TAB07","product_condition":"new"},"df_price":31,"df_sale_price":"","df_regular_price":31,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tab07-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/95233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=95233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/95234"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=95233"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=95233"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=95233"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=95233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}