{"id":95217,"date":"2019-02-03T19:58:32","date_gmt":"2019-02-03T18:58:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/"},"modified":"2026-05-09T01:52:16","modified_gmt":"2026-05-08T23:52:16","slug":"the-boat-owner-s-maintenance-book-o-connell-g-9781852530129","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/","title":{"rendered":"the boat owner&#8217;s maintenance book"},"content":{"rendered":"<p>In order to explain the principles of maintenance, the author covers the following topics with clear and concise advices: the storage and winterising of boats by methods that include careening, trailers, travel hoists and crane; hints and tips for fastenings, drilling, lifting and hydraulics; specialist repairs; overwinter improvements; galley works, bottled gas, toilet and water tank systems; steering; navigation and lightning; engine overhaul; structural beefing up; sealants, paints and metal finishes; spring slipping; the all-important &#8220;bolt-on-goodies&#8221; and the luxuries they entail.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>o&#8217;connell g.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ashford<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9781852530129<\/p>\n","protected":false},"featured_media":95218,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2565],"product_tag":[],"class_list":{"0":"post-95217","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-navigation-boat-and-systems-maintenance","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>the boat owner&#039;s maintenance book - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"the boat owner&#039;s maintenance book\" \/>\n<meta property=\"og:description\" content=\"Author: o&#039;connell g.Publisher: ashfordISBN: 9781852530129\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"461\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/\",\"name\":\"the boat owner's maintenance book - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/boatownersmaintenancebook3.jpg\",\"datePublished\":\"2019-02-03T18:58:32+00:00\",\"dateModified\":\"2026-05-08T23:52:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/boatownersmaintenancebook3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/boatownersmaintenancebook3.jpg\",\"width\":461,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"the boat owner&#8217;s maintenance book\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9781852530129\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"the boat owner's maintenance book - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/","og_locale":"en_US","og_type":"article","og_title":"the boat owner's maintenance book","og_description":"Author: o'connell g.Publisher: ashfordISBN: 9781852530129","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:52:16+00:00","og_image":[{"width":461,"height":600,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/","name":"the boat owner's maintenance book - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3.jpg","datePublished":"2019-02-03T18:58:32+00:00","dateModified":"2026-05-08T23:52:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3.jpg","width":461,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-boat-owner-s-maintenance-book-o-connell-g-9781852530129\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"the boat owner&#8217;s maintenance book"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9781852530129","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/boatownersmaintenancebook3-231x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/95217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=95217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/95218"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=95217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=95217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=95217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=95217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}