{"id":95083,"date":"2019-02-03T19:59:37","date_gmt":"2019-02-03T18:59:37","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/"},"modified":"2026-05-09T01:50:43","modified_gmt":"2026-05-08T23:50:43","slug":"tecniche-di-vela-illustrate-ivar-dedekam-9788885986404","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/","title":{"rendered":"tecniche di vela illustrate"},"content":{"rendered":"<p>Questo&nbsp;volume dimostra che <strong>la navigazione a vela &egrave; facile<\/strong>. La missione dell&#8217;autore di realizzare un libro che insegni a <strong>regolare le vele e l&#8217;attrezzatura<\/strong> &egrave; stata compiuta nella maniera pi&ugrave; <strong>semplice ed efficace<\/strong>.<\/p>\n<p>Le applicazioni suggerite in queste pagine sono state dettate dall&#8217;esperienza e dall&#8217;osservazione. <strong>Testi sintetici <\/strong>con accanto delle <strong>illustrazioni originali<\/strong> a colori spiegano pi&ugrave; di voluminosi libri e rispondono alle domande che solitamente si pone il velista alle prese con la regolazione delle vele, l&#8217;<strong>uso dello spinnaker<\/strong>, la <strong>manutenzione <\/strong>e la <strong>regolazione del sartiame<\/strong>.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>aerodinamica, regolazione delle manovre e delle vele, utilizzo dello spinnaker, manutenzione del sartiame<\/p>\n<p class=\"autore\"><span>Author: <\/span>ivar dedekam<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>incontri nautici <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788885986404<\/p>\n","protected":false},"featured_media":117140,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2755],"product_tag":[],"class_list":{"0":"post-95083","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rigging-and-sails","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tecniche di vela illustrate - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tecniche di vela illustrate\" \/>\n<meta property=\"og:description\" content=\"Subtitle: aerodinamica, regolazione delle manovre e delle vele, utilizzo dello spinnaker, manutenzione del sartiameAuthor: ivar dedekamPublisher: incontri nautici ISBN: 9788885986404\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:50:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"597\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;13,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/\",\"name\":\"tecniche di vela illustrate - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tecnichedivelaillustrate2-6.jpg\",\"datePublished\":\"2019-02-03T18:59:37+00:00\",\"dateModified\":\"2026-05-08T23:50:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tecnichedivelaillustrate2-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tecnichedivelaillustrate2-6.jpg\",\"width\":424,\"height\":597},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tecniche di vela illustrate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"13.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788885986404\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tecniche di vela illustrate - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/","og_locale":"en_US","og_type":"article","og_title":"tecniche di vela illustrate","og_description":"Subtitle: aerodinamica, regolazione delle manovre e delle vele, utilizzo dello spinnaker, manutenzione del sartiameAuthor: ivar dedekamPublisher: incontri nautici ISBN: 9788885986404","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:50:43+00:00","og_image":[{"width":424,"height":597,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;13,50","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/","name":"tecniche di vela illustrate - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6.jpg","datePublished":"2019-02-03T18:59:37+00:00","dateModified":"2026-05-08T23:50:43+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6.jpg","width":424,"height":597},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tecniche-di-vela-illustrate-ivar-dedekam-9788885986404\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tecniche di vela illustrate"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"13.50","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788885986404","product_condition":"new"},"df_price":13.5,"df_sale_price":"","df_regular_price":13.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tecnichedivelaillustrate2-6-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/95083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=95083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/117140"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=95083"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=95083"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=95083"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=95083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}