{"id":94995,"date":"2019-02-03T20:00:09","date_gmt":"2019-02-03T19:00:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/"},"modified":"2026-05-09T01:49:41","modified_gmt":"2026-05-08T23:49:41","slug":"diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/","title":{"rendered":"diving and snorkeling guide to southern california"},"content":{"rendered":"<p>This guide has been compiled by experts who know exactly the kind of information you need to make your diving or snorkeling vacation a safe and totally enjoyable experience and&nbsp;it&#8217;s illustrated with maps and exquisite underwater and topside photographs.<\/p>\n<p>Edition: 1987<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>including palos verdes, la jolla area, malibu and more<\/p>\n<p class=\"autore\"><span>Author: <\/span>sheckler d.+k.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>pisces books<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>450942279<\/p>\n","protected":false},"featured_media":94996,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2587],"product_tag":[],"class_list":{"0":"post-94995","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-diving-dive-guides","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>diving and snorkeling guide to southern california - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"diving and snorkeling guide to southern california\" \/>\n<meta property=\"og:description\" content=\"Subtitle: including palos verdes, la jolla area, malibu and moreAuthor: sheckler d.+k.Publisher: pisces booksISBN: 450942279\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/\",\"name\":\"diving and snorkeling guide to southern california - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/divingandsnorkelingguidetosoutherncalifornia.jpg\",\"datePublished\":\"2019-02-03T19:00:09+00:00\",\"dateModified\":\"2026-05-08T23:49:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/divingandsnorkelingguidetosoutherncalifornia.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/divingandsnorkelingguidetosoutherncalifornia.jpg\",\"width\":395,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"diving and snorkeling guide to southern california\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"450942279\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"diving and snorkeling guide to southern california - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/","og_locale":"en_US","og_type":"article","og_title":"diving and snorkeling guide to southern california","og_description":"Subtitle: including palos verdes, la jolla area, malibu and moreAuthor: sheckler d.+k.Publisher: pisces booksISBN: 450942279","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:49:41+00:00","og_image":[{"width":395,"height":593,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/","name":"diving and snorkeling guide to southern california - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia.jpg","datePublished":"2019-02-03T19:00:09+00:00","dateModified":"2026-05-08T23:49:41+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia.jpg","width":395,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diving-and-snorkeling-guide-to-southern-california-sheckler-d-k-450942279\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"diving and snorkeling guide to southern california"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"450942279","product_condition":"new"},"df_price":16,"df_sale_price":16,"df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/divingandsnorkelingguidetosoutherncalifornia-200x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/94996"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94995"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94995"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94995"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}