{"id":94991,"date":"2019-02-03T20:00:10","date_gmt":"2019-02-03T19:00:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/"},"modified":"2026-07-11T02:43:34","modified_gmt":"2026-07-11T00:43:34","slug":"naufrages-en-provence-fascicule-2-joncheray-j-p-258994580","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/","title":{"rendered":"naufrages en provence fascicule 2"},"content":{"rendered":"<p>Une r&eacute;f&eacute;rence incontournable, un document indispensable!<br \/>&nbsp;<br \/>Fruit de vingt cinq ann&eacute;es de recherches de Jean-Pierre Joncheray et de ses amis, il y a l&agrave; la carri&egrave;re des b&acirc;timents, leur vie avant le naufrage, les circonstances de leurs pertes<br \/>et ce qui reste de chaque &eacute;pave avec les d&eacute;tails pratiques.<\/p>\n<p>Edition: 1984<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>ou le livre des epaves<\/p>\n<p class=\"autore\"><span>Author: <\/span>joncheray j.-p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>cahiers d&#8217;archeologie subaquatique<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>258994580<\/p>\n","protected":false},"featured_media":133934,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3082,2593],"product_tag":[],"class_list":{"0":"post-94991","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1-books-diving-archeology","7":"product_cat-magazines","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>naufrages en provence fascicule 2 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"naufrages en provence fascicule 2\" \/>\n<meta property=\"og:description\" content=\"Subtitle: ou le livre des epavesAuthor: joncheray j.-p.Publisher: cahiers d&#039;archeologie subaquatiqueISBN: 258994580\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:43:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"416\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;11,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/\",\"name\":\"naufrages en provence fascicule 2 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/naufragesenprovence2-1.jpg\",\"datePublished\":\"2019-02-03T19:00:10+00:00\",\"dateModified\":\"2026-07-11T00:43:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/naufragesenprovence2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/naufragesenprovence2-1.jpg\",\"width\":416,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"naufrages en provence fascicule 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"11.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"258994580\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"naufrages en provence fascicule 2 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/","og_locale":"en_US","og_type":"article","og_title":"naufrages en provence fascicule 2","og_description":"Subtitle: ou le livre des epavesAuthor: joncheray j.-p.Publisher: cahiers d'archeologie subaquatiqueISBN: 258994580","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:43:34+00:00","og_image":[{"width":416,"height":593,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;11,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/","name":"naufrages en provence fascicule 2 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1.jpg","datePublished":"2019-02-03T19:00:10+00:00","dateModified":"2026-07-11T00:43:34+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1.jpg","width":416,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/naufrages-en-provence-fascicule-2-joncheray-j-p-258994580\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"naufrages en provence fascicule 2"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"11.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"258994580","product_condition":"new"},"df_price":11,"df_sale_price":11,"df_regular_price":17.04,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/naufragesenprovence2-1-210x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/133934"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94991"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94991"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}