{"id":94941,"date":"2019-02-03T20:00:29","date_gmt":"2019-02-03T19:00:29","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/corallo-rosso-fusco-l-9788879475372\/"},"modified":"2026-05-09T01:49:03","modified_gmt":"2026-05-08T23:49:03","slug":"corallo-rosso-fusco-l-9788879475372","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/","title":{"rendered":"corallo rosso"},"content":{"rendered":"<p>Questo &egrave; un libro pieno di vita e di inconsapevole poesia, un libro che ci fa assistere non solo allo spettacolo del mare sopra e sotto, nelle sue trasparenze e nelle sue magiche profondit&agrave;, ma &egrave; anche il ritratto di un uomo che sente di avere una missione, che ha trovato nel mare il suo elemento e la sua ragione di vita, il suo lavoro e il suo sostento, il legame che lo unisce ad altri uomini come lui associati nella stessa impresa, l&rsquo;occasione di affrontare disagi e pericoli anche mortali e, infine, l&rsquo;amore di una donna. Il motivo che ha spinto&nbsp;l&#8217;autore a scrivere &egrave; stato il desiderio di denunciare al mondo, come un vero e proprio crimine con la Natura, la scomparsa dalle acque del Tirreno del corallo rosso, il pi&ugrave; pregiato, quello che si trovava fino a pochi anni fa sulle coste orientali della Sardegna. La scomparsa dovuta alla pesca indiscriminata fatta dalle &#8220;coralline&#8221; col pesante &#8220;ingegno&#8221; di ferro che strascicato sul fondo tutto devasta come un bulldozer e seppellisce nel fango &egrave; un danno irreparabile. Tutto questo &egrave; all&rsquo;origine, &egrave; la motivazione interna del libro, che&nbsp;si legge come un racconto autobiografico che inizia dall&rsquo;adolescenza (quando l&rsquo;autore usciva per mare la notte con i pescatori alla pesca con la lampara e ne condivideva le fatiche e le antiche abitudini o quando audacemente si immergeva in apnea e passava sotto l&rsquo;arco da cui arrivava la luce che invadeva la Grotta Azzurra di Palinuro provocandone i riflessi) fino a quando, dopo aver navigato dai Caraibi al Mar del Giappone, dal Marocco alla Tunisia, sempre alla ricerca del corallo, conclude la sua affascinante avventura e la descrive in questo libro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>fusco l.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni idelson-gnocchi 1908<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788879475372<\/p>\n","protected":false},"featured_media":147267,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2589,3075],"product_tag":[],"class_list":{"0":"post-94941","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-books-diving-literature","8":"product_cat-saltwater","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>corallo rosso - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"corallo rosso\" \/>\n<meta property=\"og:description\" content=\"Author: fusco l.Publisher: edizioni idelson-gnocchi 1908ISBN: 9788879475372\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:49:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"419\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;30,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/\",\"name\":\"corallo rosso - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/corallorosso3-5.jpg\",\"datePublished\":\"2019-02-03T19:00:29+00:00\",\"dateModified\":\"2026-05-08T23:49:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/corallorosso3-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/corallorosso3-5.jpg\",\"width\":419,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/corallo-rosso-fusco-l-9788879475372\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"corallo rosso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788879475372\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"corallo rosso - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/","og_locale":"en_US","og_type":"article","og_title":"corallo rosso","og_description":"Author: fusco l.Publisher: edizioni idelson-gnocchi 1908ISBN: 9788879475372","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:49:03+00:00","og_image":[{"width":419,"height":594,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;30,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/","name":"corallo rosso - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5.jpg","datePublished":"2019-02-03T19:00:29+00:00","dateModified":"2026-05-08T23:49:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5.jpg","width":419,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/corallo-rosso-fusco-l-9788879475372\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"corallo rosso"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788879475372","product_condition":"new"},"df_price":30,"df_sale_price":"","df_regular_price":30,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/corallorosso3-5-212x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/147267"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94941"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94941"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94941"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}