{"id":94616,"date":"2019-02-03T20:03:00","date_gmt":"2019-02-03T19:03:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/"},"modified":"2026-07-11T02:37:17","modified_gmt":"2026-07-11T00:37:17","slug":"tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/","title":{"rendered":"tattica e regolamento di regata di surf"},"content":{"rendered":"<p>Questo volume raccoglie una serie di testi di Klaus Maran, il pi&ugrave; grande surfer italiano, e di Alberto Bracchi, noto giornalista del settore. In esso i lettori troveranno tutto ci&ograve; che si deve sapere sia dal punto di vista pratico sia dal punto di vista teorico sulle regate di surf. Maran rivela le tecniche da lui usate durante le gare e fornisce una quantit&agrave; di preziosi consigli pratici per sconfiggere gli avversari e arrivare felicemente sulla linea del traguardo. Bracchi, invece, prende in esame il regolamento di regata e spiega come la sua corretta conoscenza possa aiutare ad evitare spiacevoli situazioni ed essere utile per conseguire la vittoria.<\/p>\n<p>Edizione: 1985<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>maran k.  bracchi a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842587316<\/p>\n","protected":false},"featured_media":133806,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3079],"product_tag":[],"class_list":{"0":"post-94616","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitesurf-sup-and-windsurf","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tattica e regolamento di regata di surf - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tattica e regolamento di regata di surf\" \/>\n<meta property=\"og:description\" content=\"Author: maran k. bracchi a.Publisher: Ugo Mursia EditoreISBN: 9788842587316\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:37:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"376\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,30\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/\",\"name\":\"tattica e regolamento di regata di surf - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg\",\"datePublished\":\"2019-02-03T19:03:00+00:00\",\"dateModified\":\"2026-07-11T00:37:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg\",\"width\":376,\"height\":596},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"tattica e regolamento di regata di surf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.30\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842587316\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tattica e regolamento di regata di surf - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/","og_locale":"en_US","og_type":"article","og_title":"tattica e regolamento di regata di surf","og_description":"Author: maran k. bracchi a.Publisher: Ugo Mursia EditoreISBN: 9788842587316","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:37:17+00:00","og_image":[{"width":376,"height":596,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,30","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/","name":"tattica e regolamento di regata di surf - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg","datePublished":"2019-02-03T19:03:00+00:00","dateModified":"2026-07-11T00:37:17+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1.jpg","width":376,"height":596},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/tattica-e-regolamento-di-regata-di-surf-maran-k-bracchi-a-9788842587316\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"tattica e regolamento di regata di surf"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.30","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788842587316","product_condition":"new"},"df_price":9.3,"df_sale_price":"","df_regular_price":9.3,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tatticaeregolamentodiregatadisurf-maranbracchi-1-189x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/133806"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94616"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94616"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94616"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}