{"id":94346,"date":"2019-02-03T20:05:03","date_gmt":"2019-02-03T19:05:03","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/carta-nautica-n-12-ukho12\/"},"modified":"2026-07-11T02:32:44","modified_gmt":"2026-07-11T00:32:44","slug":"carta-nautica-n-12-ukho12","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/","title":{"rendered":"carta nautica n.   12"},"content":{"rendered":"<p>&#8211; Al Aqabah to Duba and ports on the coast of Saudi Arabia (Scala: 1:350.000)<\/p>\n<p>&#8211; A: Ash&nbsp;Sharmah (Scala: 1:75.000)<\/p>\n<p>&#8211; B: Approaches to Duba (Scala: 1:150.000)<\/p>\n<p>&#8211; C: Port of Duba (Scala: 1:15.000)<\/p>\n<p>&#8211; D: Duba Bulk Plant Terminal (Scala: 1:10.000)<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>al aqabah to duba and ports on the coast of saudi arabia<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>united kingdom hydrographic office (ukho)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>UKHO12<\/p>\n","protected":false},"featured_media":58287,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2540,2538],"product_tag":[],"class_list":{"0":"post-94346","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-northern-part","7":"product_cat-overview-red-sea-and-gulf-of-aden","8":"product_shipping_class-formato-spedizione","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>carta nautica n.  12 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carta nautica n.  12\" \/>\n<meta property=\"og:description\" content=\"Subtitle: al aqabah to duba and ports on the coast of saudi arabiaManufacturer: united kingdom hydrographic office (ukho)ISBN: UKHO12\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;67,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/\",\"name\":\"carta nautica n. 12 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg\",\"datePublished\":\"2019-02-03T19:05:03+00:00\",\"dateModified\":\"2026-07-11T00:32:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg\",\"width\":300,\"height\":442},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-nautica-n-12-ukho12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"carta nautica n. 12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"67.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"UKHO12\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"carta nautica n.  12 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/","og_locale":"en_US","og_type":"article","og_title":"carta nautica n.  12","og_description":"Subtitle: al aqabah to duba and ports on the coast of saudi arabiaManufacturer: united kingdom hydrographic office (ukho)ISBN: UKHO12","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:32:44+00:00","og_image":[{"width":300,"height":442,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;67,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/","name":"carta nautica n. 12 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg","datePublished":"2019-02-03T19:05:03+00:00","dateModified":"2026-07-11T00:32:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1.jpg","width":300,"height":442},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-nautica-n-12-ukho12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"carta nautica n. 12"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"67.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"UKHO12","product_condition":"new"},"df_price":67,"df_sale_price":"","df_regular_price":67,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cartanautica12alaqabahtodubaandportsonthecoastofsaudiarabia-1-204x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/58287"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94346"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94346"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94346"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}