{"id":94327,"date":"2019-02-03T20:05:06","date_gmt":"2019-02-03T19:05:06","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/"},"modified":"2026-07-11T02:32:26","modified_gmt":"2026-07-11T00:32:26","slug":"isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/","title":{"rendered":"isole dahlak"},"content":{"rendered":"<p>L&rsquo;abbondanza di uccelli marini, la ricchezza di una barriera corallina che non teme il riscaldamento globale, i branchi di gazzelle che sopravvivono nonostante la siccit&agrave; sono i segni di una natura giunta quasi intatta all&rsquo;inizio del XXI secolo. Seguendo i ritmi di questa natura scorre anche la semplice e tradizionale vita degli abitanti di queste isole, mentre dal suolo riarso emergono, ancora poco studiati e valorizzati, i resti archeologici delle civilt&agrave; che per due millenni si sono succedute nel controllo di queste isole, crocevia delle rotte commerciali tra Mediterraneo, Corno d&rsquo;Africa e Oriente. Il libro illustra la vita delle Isole Dahlak in tutti i suoi aspetti: quello naturalistico, nei suoi ambienti marini, costieri e terrestri; quello storico, con un&rsquo;ampia ricostruzione delle civilt&agrave; che si sono contese in passato l&rsquo;arcipelago; quello etnografico, con un tuffo nella vita e nelle tradizioni degli attuali abitanti delle isole. Una ricca sezione &egrave;&nbsp;dedicata ai turisti, con una guida dettagliata alle singole isole e alle possibilit&agrave; di godere appieno di tutta la loro incontaminata bellezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>un arcipelago del mar rosso eritreo<\/p>\n<p class=\"autore\"><span>Author: <\/span>de marchi g.  montesanto g.  traverso g.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Erga Edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788881637423<\/p>\n","protected":false},"featured_media":82735,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2646],"product_tag":[],"class_list":{"0":"post-94327","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-world-picture-books-tourism","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>isole dahlak - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"isole dahlak\" \/>\n<meta property=\"og:description\" content=\"Subtitle: un arcipelago del mar rosso eritreoAuthor: de marchi g. montesanto g. traverso g.Publisher: Erga EdizioniISBN: 9788881637423\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"476\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/\",\"name\":\"isole dahlak - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledahlakerga-1.jpg\",\"datePublished\":\"2019-02-03T19:05:06+00:00\",\"dateModified\":\"2026-07-11T00:32:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledahlakerga-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledahlakerga-1.jpg\",\"width\":476,\"height\":593},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"isole dahlak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788881637423\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"isole dahlak - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/","og_locale":"en_US","og_type":"article","og_title":"isole dahlak","og_description":"Subtitle: un arcipelago del mar rosso eritreoAuthor: de marchi g. montesanto g. traverso g.Publisher: Erga EdizioniISBN: 9788881637423","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:32:26+00:00","og_image":[{"width":476,"height":593,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/","name":"isole dahlak - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1.jpg","datePublished":"2019-02-03T19:05:06+00:00","dateModified":"2026-07-11T00:32:26+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1.jpg","width":476,"height":593},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dahlak-de-marchi-g-montesanto-g-traverso-g-9788881637423\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"isole dahlak"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788881637423","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledahlakerga-1-241x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/94327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=94327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/82735"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=94327"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=94327"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=94327"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=94327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}