{"id":93998,"date":"2019-02-03T20:07:25","date_gmt":"2019-02-03T19:07:25","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/vistona-borea-d-olmo-g-b-borea-d-olmo-o-gallo-g-22995974238038\/"},"modified":"2026-07-11T02:26:51","modified_gmt":"2026-07-11T00:26:51","slug":"vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/","title":{"rendered":"vistona"},"content":{"rendered":"<p>Dall&#8217;introduzione: &#8220;Grazie alla ricerca, eseguita con la preziosa collaborazione di Chicco Zaccagni e collegandomi alle note di Gian Marco Borea, &egrave; svelata l&#8217;intera storia di &#8220;Vistona&#8221;. Ottant&#8217;anni in cui ha macinato miglia come poche altre della sua categoria, grazie soprattutto a due &#8220;gentlemen sailors&#8221;, il primo armatore e l&#8217;ultimo, che ne hanno saputo apprezzare le qualit&agrave;&#8221;.<\/p>\n<p>Edizione: 2016<\/p>\n<p>Costo del libro &euro; 38,00 + &euro; 7,00 per la consegna in libreria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>i primi ottant&#8217;anni di una barca leggendaria<\/p>\n<p class=\"autore\"><span>Author: <\/span>gian battista e ottavia borea d&#8217;olmo &#8211; giuliano gallo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>yachting library<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>22995974238038<\/p>\n","protected":false},"featured_media":143842,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3007,2576],"product_tag":[],"class_list":{"0":"post-93998","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monographs","7":"product_cat-books-navigation-illustrated-books","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>vistona - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vistona\" \/>\n<meta property=\"og:description\" content=\"Subtitle: i primi ottant&#039;anni di una barca leggendariaAuthor: gian battista e ottavia borea d&#039;olmo - giuliano galloPublisher: yachting libraryISBN: 22995974238038\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;46,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/\",\"name\":\"vistona - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vistona-8.jpg\",\"datePublished\":\"2019-02-03T19:07:25+00:00\",\"dateModified\":\"2026-07-11T00:26:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vistona-8.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vistona-8.jpg\",\"width\":777,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"vistona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"46.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"22995974238038\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"vistona - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/","og_locale":"en_US","og_type":"article","og_title":"vistona","og_description":"Subtitle: i primi ottant'anni di una barca leggendariaAuthor: gian battista e ottavia borea d'olmo - giuliano galloPublisher: yachting libraryISBN: 22995974238038","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:26:51+00:00","og_image":[{"width":777,"height":599,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;46,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/","name":"vistona - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8.jpg","datePublished":"2019-02-03T19:07:25+00:00","dateModified":"2026-07-11T00:26:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8.jpg","width":777,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vistona-gian-battista-e-ottavia-borea-d-olmo-giuliano-gallo-22995974238038\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"vistona"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"46.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"22995974238038","product_condition":"new"},"df_price":46,"df_sale_price":"","df_regular_price":46,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vistona-8-300x231.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/93998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=93998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/143842"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=93998"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=93998"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=93998"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=93998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}