{"id":93977,"date":"2019-02-03T20:48:26","date_gmt":"2019-02-03T19:48:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/forte-come-l-onda-il-mio-amore-zingoni-f-9788864115849\/"},"modified":"2026-05-09T01:38:14","modified_gmt":"2026-05-08T23:38:14","slug":"forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/","title":{"rendered":"forte come l&#8217;onda \u00e8 il mio amore"},"content":{"rendered":"<p>Buttato sulla sabbia, accecato dal fulgore di un paradiso perduto, le palpebre incollate dal sale, riapro gli occhi. La mia mente &egrave; vuota: nessun ricordo, nessuna parola. Una tabula rasa. Non posso formulare un pensiero. Non so pi&ugrave; distinguere i miei sentimenti, dare ordine alle mie percezioni. Qualcosa che non conosco ha annientato la mia vita. &Egrave; un sogno a salvarmi: il viso luminoso di una donna. Impossibile per me riconoscerla o ricordare il suo nome. Ma quel sorriso mi riscuote dall&rsquo;oblio, diventa l&rsquo;unica ragione per sopravvivere e fuggire. A guidarmi &egrave; un libro, trascinato sulla spiaggia dalla mareggiata di un tifone. Tra le sue pagine distrutte si &egrave; salvata solo una misteriosa poesia. E sembra parlare di me. Attraverser&ograve; il mondo per sapere chi sei. Vestir&ograve; nuove identit&agrave; per ritrovarti. Cavalcher&ograve; un&rsquo;onda paurosa per scoprire cosa nasconde il suo cono d&rsquo;ombra: il nostro ultimo segreto, cancellato dall&rsquo;amnesia. E alla fine sapremo solo una cosa, la pi&ugrave; grande. Forte come quest&rsquo;onda che nessuno pu&ograve; cavalcare fino in fondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>zingoni f.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Fazi Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788864115849<\/p>\n","protected":false},"featured_media":108263,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2809],"product_tag":[],"class_list":{"0":"post-93977","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-novels","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>forte come l&#039;onda \u00e8 il mio amore - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"forte come l&#039;onda \u00e8 il mio amore\" \/>\n<meta property=\"og:description\" content=\"Author: zingoni f.Publisher: Fazi EditoreISBN: 9788864115849\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:38:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"397\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/\",\"name\":\"forte come l'onda \u00e8 il mio amore - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fortecomelondaeilmioamore2-1.jpg\",\"datePublished\":\"2019-02-03T19:48:26+00:00\",\"dateModified\":\"2026-05-08T23:38:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fortecomelondaeilmioamore2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fortecomelondaeilmioamore2-1.jpg\",\"width\":397,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"forte come l&#8217;onda \u00e8 il mio amore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788864115849\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"forte come l'onda \u00e8 il mio amore - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/","og_locale":"en_US","og_type":"article","og_title":"forte come l'onda \u00e8 il mio amore","og_description":"Author: zingoni f.Publisher: Fazi EditoreISBN: 9788864115849","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:38:14+00:00","og_image":[{"width":397,"height":605,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/","name":"forte come l'onda \u00e8 il mio amore - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1.jpg","datePublished":"2019-02-03T19:48:26+00:00","dateModified":"2026-05-08T23:38:14+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1.jpg","width":397,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/forte-come-l-onda-e-il-mio-amore-zingoni-f-9788864115849\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"forte come l&#8217;onda \u00e8 il mio amore"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788864115849","product_condition":"new"},"df_price":17.5,"df_sale_price":"","df_regular_price":17.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fortecomelondaeilmioamore2-1-197x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/93977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=93977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/108263"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=93977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=93977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=93977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=93977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}