{"id":93932,"date":"2019-02-21T16:42:23","date_gmt":"2019-02-21T15:42:23","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/lo-yacht-sciarrelli-c-9788842522683\/"},"modified":"2026-07-11T02:25:12","modified_gmt":"2026-07-11T00:25:12","slug":"lo-yacht-carlo-sciarrelli-9788842513520","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/","title":{"rendered":"lo yacht"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>Raro esemplare della prima edizione del Gruppo Ugo Mursia del 1970 ristampata nel 1992 in perfetto stato di conservazione, collana &ldquo;Biblioteca del Mare&rdquo; 29 (Le strenne del mare 4). In-8, legatura editoriale telata blu con impressioni oro al piatto anteriore e al dorso; sovraccoperta in carta plastificata illustrata a colori (appena rovinata al dorso) con alette; 488 pp., con risguardi illustrati in azzurro, frontespizio stampato in azzurro e nero, 36 fotografie e 259 disegni in nero nel testo e 20 tavole a colori fuori testo.<\/strong><\/p>\n<p>Dall&rsquo;aletta anteriore: <em>Le <\/em>barche<em> come esseri viventi: cos&igrave; le vede e ce le fa vedere l&rsquo;Autore, costruttore egli stesso di yacht non <\/em>in serie<em> ma, per cos&igrave; dire, su misura.<\/em><\/p>\n<p><em>Perci&ograve; in queste pagine l&#8217;abbondantissimo corredo di piani e di dati costruttivi non riveste solo una funzione tecnica; esso permette soprattutto al lettore di partecipare all&#8217;intima natura dei singoli yacht, rendendolo sensibile alla loro individualit&agrave;.<\/em><\/p>\n<p><em>Tutti gli yacht famosi e meno famosi, che dalle origini a oggi hanno <\/em>contato<em>, rivivono in questo libro, con le loro caratteristiche, i loro risultati pratici, i loro capricci e le loro imprese.<\/em><\/p>\n<p><em>Le splendide tavole a colori, tra cui quelle dovute a Beken di Cowes (i Beken, da varie generazioni, sono i maggiori fotografi di marina del mondo), mostrano in azione le barche, con tutto il fascino che emanano quando le vediamo sul mare. Il testo e le illustrazioni che lo accompagnano ci fanno capire pi&ugrave; da vicino il segreto della loro grazia, della loro forza e della loro velocit&agrave;. [&#8230;]<\/em><\/p>\n<p><em>Oltre 200 yacht passano davanti agli occhi del lettore, non come semplici e inerti citazioni, ma presentandosi con la loro autentica&nbsp;<\/em>personalit&agrave;<em>, e in relazione alla loro vita sul mare, al loro temperamento e alle circostanze in cui furono coinvolti. <\/em><em>L&rsquo;attenzione speciale rivolta allo scafo degli yacht &egrave; abbastanza naturale, da parte di un Autore che &egrave; anche costruttore; ma risulta anche rivelatrice della parte preminente dello scafo e delle sue caratteristiche nella <\/em>performance<em> di qualsiasi barca.<\/em><\/p>\n<p style=\"text-align: justify\"><em>La vivacit&agrave; dell&rsquo;esposizione, la completezza delle notizie e della documentazione visiva (mai, forse, sono state raccolte e messe a confronto le caratteristiche strutturali di tanti yacht di ogni tempo), e specialmente la passione <\/em>ragionata<em>&nbsp;con la quale viene rievocata la vicenda dello yacht, fanno di quest&rsquo;opera un libro nuovo, che si distacca da ogni altra storia delle imbarcazioni da diporto.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>origine ed evoluzione del veliero da diporto<\/p>\n<p class=\"autore\"><span>Author: <\/span>carlo sciarrelli<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842513520<\/p>\n","protected":false},"featured_media":127771,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2788,2606,3007],"product_tag":[],"class_list":{"0":"post-93932","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tiger-shark","7":"product_cat-encyclopedias-atlases-and-handbooks","8":"product_cat-monographs","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lo yacht - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lo yacht\" \/>\n<meta property=\"og:description\" content=\"Subtitle: origine ed evoluzione del veliero da diportoAuthor: carlo sciarrelliPublisher: Ugo Mursia EditoreISBN: 9788842513520\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:25:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"591\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;99,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/\",\"name\":\"lo yacht - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg\",\"datePublished\":\"2019-02-21T15:42:23+00:00\",\"dateModified\":\"2026-07-11T00:25:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg\",\"width\":591,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lo-yacht-carlo-sciarrelli-9788842513520\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"lo yacht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"99.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842513520\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lo yacht - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/","og_locale":"en_US","og_type":"article","og_title":"lo yacht","og_description":"Subtitle: origine ed evoluzione del veliero da diportoAuthor: carlo sciarrelliPublisher: Ugo Mursia EditoreISBN: 9788842513520","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:25:12+00:00","og_image":[{"width":591,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;99,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/","name":"lo yacht - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg","datePublished":"2019-02-21T15:42:23+00:00","dateModified":"2026-07-11T00:25:12+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5.jpg","width":591,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lo-yacht-carlo-sciarrelli-9788842513520\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"lo yacht"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"99.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788842513520","product_condition":"new"},"df_price":99,"df_sale_price":"","df_regular_price":99,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lo-yacht-carlo-sciarrelli-mursia-1992-5-253x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/93932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=93932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127771"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=93932"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=93932"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=93932"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=93932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}