{"id":93193,"date":"2019-02-03T19:47:08","date_gmt":"2019-02-03T18:47:08","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storia-dei-filibustieri-sternbeck-a-9788862883665\/"},"modified":"2026-07-11T03:14:45","modified_gmt":"2026-07-11T01:14:45","slug":"storia-dei-filibustieri-sternbeck-a-9788862883665","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/","title":{"rendered":"storia dei filibustieri"},"content":{"rendered":"<p>La Filibusta, associazione di corsari e pirati venuti da Francia, Inghilterra e Paesi Bassi e rifugiatisi sull&#8217;Isola Tortuga (a nord di Haiti) per allearsi contro gli spagnoli, oper&ograve; nel Golfo del Messico nella seconda met&agrave; del Seicento, devastando insieme ai bucanieri, che operavano nell&#8217;entroterra le coste del Mar dei Caraibi. Sternbeck ci fa rivivere il vagabondaggio inquieto di uomini straordinari, gli alti e bassi delle loro avventure. Nel gioco delle onde si sentono i desideri, l&#8217;aspirazione alla libert&agrave;, i giuramenti, le delusioni, le speranze; e nella collera dei venti e dei marosi si intuiscono nuove cadute. Un racconto fantastico in chiaroscuro dove si mischiano angosciose chiamate di amrinai, tonanti ordini dei comandanti, acute strida di gabbiani&#8230; storie di pirati eccellenti, uomini d&#8217;arme e d&#8217;avventura (da Francesco Nau detto l&#8217;Olonese a Henry Morgan e Capitano Kidd) che liberano al vento il Jolly Roger e impavidi sfidano la&nbsp;morte!<\/p>\n<p>Edizione: 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>sternbeck a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Casa Editrice Odoya<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862883665<\/p>\n","protected":false},"featured_media":132773,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3063],"product_tag":[],"class_list":{"0":"post-93193","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-essays-books-navigation-history-pirates","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storia dei filibustieri - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storia dei filibustieri\" \/>\n<meta property=\"og:description\" content=\"Author: sternbeck a.Publisher: Casa Editrice OdoyaISBN: 9788862883665\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:14:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/\",\"name\":\"storia dei filibustieri - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadeifilibustieri-sternbeck-1.jpg\",\"datePublished\":\"2019-02-03T18:47:08+00:00\",\"dateModified\":\"2026-07-11T01:14:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadeifilibustieri-sternbeck-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadeifilibustieri-sternbeck-1.jpg\",\"width\":360,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-dei-filibustieri-sternbeck-a-9788862883665\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storia dei filibustieri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862883665\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storia dei filibustieri - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/","og_locale":"en_US","og_type":"article","og_title":"storia dei filibustieri","og_description":"Author: sternbeck a.Publisher: Casa Editrice OdoyaISBN: 9788862883665","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:14:45+00:00","og_image":[{"width":360,"height":565,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/","name":"storia dei filibustieri - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1.jpg","datePublished":"2019-02-03T18:47:08+00:00","dateModified":"2026-07-11T01:14:45+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1.jpg","width":360,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-dei-filibustieri-sternbeck-a-9788862883665\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storia dei filibustieri"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862883665","product_condition":"new"},"df_price":22,"df_sale_price":"","df_regular_price":22,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadeifilibustieri-sternbeck-1-191x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/93193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=93193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/132773"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=93193"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=93193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=93193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=93193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}