{"id":93023,"date":"2019-02-03T19:48:16","date_gmt":"2019-02-03T18:48:16","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/"},"modified":"2026-07-11T03:11:51","modified_gmt":"2026-07-11T01:11:51","slug":"the-new-boatkeeper-gladstone-b-edited-by-9780380799343","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/","title":{"rendered":"the new boatkeeper"},"content":{"rendered":"<p>&#8211; The lastest in how-to techniques: how to patch and repair fiberglass, how to finish wood trim like an expert, how to protect against and repair hull blisters, how to find and repair leaks and how to make dozens of improvements that will make boating more pleasurable for every reader.<\/p>\n<p>&#8211; In-depth information about the newest and most useful tools, sealants, adhesives and other products that speed and simplify all boat maintenance and repair.<\/p>\n<p>&#8211; Everything you need to know to properly lay up the boat at the end of the season and then commission it again in the spring, regardless of whether you are doing the work yourself or are having it done by a local boatyard.<\/p>\n<p>&#8211; Advice for dealing with cruising emergencies, plus dozens of helpful pointers on how to make your boat safer, more seaworthy, more comfortable and more economical to operate.<\/p>\n<p>Edition: 1999<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>authoritative guide to maintenance, repair and improvement<\/p>\n<p class=\"autore\"><span>Author: <\/span>gladstone b. (edited by)<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>hearst books<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9780380799343<\/p>\n","protected":false},"featured_media":93024,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2577],"product_tag":[],"class_list":{"0":"post-93023","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-motorboating-and-marine-engines","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>the new boatkeeper - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"the new boatkeeper\" \/>\n<meta property=\"og:description\" content=\"Subtitle: authoritative guide to maintenance, repair and improvementAuthor: gladstone b. (edited by)Publisher: hearst booksISBN: 9780380799343\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/\",\"name\":\"the new boatkeeper - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/newboatkeeper-gladstone.jpg\",\"datePublished\":\"2019-02-03T18:48:16+00:00\",\"dateModified\":\"2026-07-11T01:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/newboatkeeper-gladstone.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/newboatkeeper-gladstone.jpg\",\"width\":323,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"the new boatkeeper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9780380799343\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"the new boatkeeper - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/","og_locale":"en_US","og_type":"article","og_title":"the new boatkeeper","og_description":"Subtitle: authoritative guide to maintenance, repair and improvementAuthor: gladstone b. (edited by)Publisher: hearst booksISBN: 9780380799343","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:11:51+00:00","og_image":[{"width":323,"height":475,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/","name":"the new boatkeeper - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone.jpg","datePublished":"2019-02-03T18:48:16+00:00","dateModified":"2026-07-11T01:11:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone.jpg","width":323,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-new-boatkeeper-gladstone-b-edited-by-9780380799343\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"the new boatkeeper"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9780380799343","product_condition":"new"},"df_price":16,"df_sale_price":16,"df_regular_price":23,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/newboatkeeper-gladstone-204x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/93023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=93023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/93024"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=93023"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=93023"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=93023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=93023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}