{"id":92875,"date":"2019-02-03T19:49:20","date_gmt":"2019-02-03T18:49:20","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/isole-islands-of-sicily-aa-vv-9788895218632\/"},"modified":"2026-07-11T03:09:15","modified_gmt":"2026-07-11T01:09:15","slug":"isole-islands-of-sicily-aa-vv-9788895218632","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/","title":{"rendered":"isole &#8211; islands of sicily"},"content":{"rendered":"<p>Isolamento, isolato, isolante, isolare: tutte voci con la stessa etimologia che ci rimandano a una dimensione di autonomia e separazione da ci&ograve; che c&rsquo;&egrave; intorno. A questo gruppo di parole appartiene anche il termine isola, che per sua definizione &egrave; una superficie emersa limitata e interamente circondata dall&rsquo;acqua. Un piccolo universo a s&eacute; stante, dunque, con confini ben definiti e lontano dalla terraferma. Un luogo particolare? Sicuramente s&igrave;, anche perch&eacute; &egrave; regolato da ritmi, abitudini e necessit&agrave; proprie che lo rendono unico e irriproducibile. Per scoprire questa &#8220;nuova dimensione&#8221;, la Sicilia offre ben tre arcipelaghi da visitare: a nord quello delle Eolie con Ustica, a ovest le Egadi e a sud le Pelagie con Pantelleria. Tre gruppi di piccole isole che, per&ograve;, non si assomigliano tra loro e offrono ai loro visitatori vacanze molto diverse.<\/p>\n<p>Lingue: Italiano e Inglese<\/p>\n<p>Isolation, isolated, insulating, insulated: each of these words has the same root that recalls a dimension of independence and separation from all that surrounds it. The word &#8220;island&#8221; also belongs to this group of words and by definition is a surface which is above sea-level and is entirely surrounded by water. A small universe of itself, therefore, with well defined borders and at a certain distance from the mainland. Without a doubt a special kind of place, as it is driven by its own rhythms, habits and needs that render it unique and one-of-akind. Sicily offers three archipelagos that present the opportunity to discover this &#8220;new dimension&#8221;. To the north are the Aeolian Islands with Ustica, to the west are the Egadi Islands and to the south the Pelagie Islands with Pantelleria. These three groups of small islands do not resemble each other at all and offer the visitor very different vacations.<\/p>\n<p>Languages: English and Italian<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>sime books<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788895218632<\/p>\n","protected":false},"featured_media":135448,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3110],"product_tag":[],"class_list":{"0":"post-92875","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-italy-picture-books-tourism","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>isole - islands of sicily - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"isole - islands of sicily\" \/>\n<meta property=\"og:description\" content=\"Author: aa.vv.Publisher: sime booksISBN: 9788895218632\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:09:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;11,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/\",\"name\":\"isole - islands of sicily - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-islandssicily-3.jpg\",\"datePublished\":\"2019-02-03T18:49:20+00:00\",\"dateModified\":\"2026-07-11T01:09:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-islandssicily-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-islandssicily-3.jpg\",\"width\":595,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-islands-of-sicily-aa-vv-9788895218632\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"isole &#8211; islands of sicily\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"11.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788895218632\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"isole - islands of sicily - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/","og_locale":"en_US","og_type":"article","og_title":"isole - islands of sicily","og_description":"Author: aa.vv.Publisher: sime booksISBN: 9788895218632","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:09:15+00:00","og_image":[{"width":595,"height":603,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;11,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/","name":"isole - islands of sicily - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3.jpg","datePublished":"2019-02-03T18:49:20+00:00","dateModified":"2026-07-11T01:09:15+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3.jpg","width":595,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-islands-of-sicily-aa-vv-9788895218632\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"isole &#8211; islands of sicily"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"11.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788895218632","product_condition":"new"},"df_price":11.9,"df_sale_price":"","df_regular_price":11.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-islandssicily-3-296x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/92875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=92875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135448"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=92875"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=92875"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=92875"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=92875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}