{"id":92847,"date":"2019-02-03T19:49:34","date_gmt":"2019-02-03T18:49:34","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/rigging-petersson-l-9781861762375\/"},"modified":"2026-05-09T02:06:24","modified_gmt":"2026-05-09T00:06:24","slug":"rigging-lennarth-petersson-9781848322189","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/","title":{"rendered":"rigging"},"content":{"rendered":"<p>Employing <strong>superb, clear draughtsmanship<\/strong> this book illustrates <strong>each and every detail of the rigging of typical period fore-and-aft vessels<\/strong>.<\/p>\n<p>The rigging of period ship models is arguably the most complex task that any modeller has to accomplish; the intricacies can be daunting and visual references limited. The author&#8217;s first book, <em>Rigging Period Ship Models<\/em>, was a triumph of clarity for those needing to decipher the complexities of square rig and has now sold in multiple editions. This book does the same for fore-and-aft craft and deploys three <strong>typical Eighteenth-century types<\/strong> &ndash; <strong>an English cutter, a three-masted French lugger and an American schooner<\/strong>. <strong>Some 200 diagrams<\/strong> show clearly where <strong>each separate item of standing and running rigging<\/strong> is fitted, led and belayed. Whatever the requirements of the modelmaker, all the information is here.<\/p>\n<p>This <strong>new paperback edition<\/strong> brings a visual clarity to the complexities of period rigging and will delight anyone with an interest in the rigging of traditional fore-and-aft craft.<\/p>\n<p>Edition: 2007<\/p>\n<p>Reprinted: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>period fore-and-aft craft<\/p>\n<p class=\"autore\"><span>Author: <\/span>lennarth petersson<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>seaforth publishing (pen &amp; sword books)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9781848322189<\/p>\n","protected":false},"featured_media":145247,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3005],"product_tag":[],"class_list":{"0":"post-92847","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-publications","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>rigging - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rigging\" \/>\n<meta property=\"og:description\" content=\"Subtitle: period fore-and-aft craftAuthor: lennarth peterssonPublisher: seaforth publishing (pen &amp; sword books)ISBN: 9781848322189\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:06:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;37,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/\",\"name\":\"rigging - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg\",\"datePublished\":\"2019-02-03T18:49:34+00:00\",\"dateModified\":\"2026-05-09T00:06:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg\",\"width\":500,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rigging-lennarth-petersson-9781848322189\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"rigging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"37.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9781848322189\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"rigging - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/","og_locale":"en_US","og_type":"article","og_title":"rigging","og_description":"Subtitle: period fore-and-aft craftAuthor: lennarth peterssonPublisher: seaforth publishing (pen &amp; sword books)ISBN: 9781848322189","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:06:24+00:00","og_image":[{"width":500,"height":720,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;37,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/","name":"rigging - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg","datePublished":"2019-02-03T18:49:34+00:00","dateModified":"2026-05-09T00:06:24+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1.jpg","width":500,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rigging-lennarth-petersson-9781848322189\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"rigging"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"37.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9781848322189","product_condition":"new"},"df_price":37,"df_sale_price":"","df_regular_price":37,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rigging-period-fore-and-aft-craft-lennarth-petersson-seaforth-publishing-1-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/92847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=92847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/145247"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=92847"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=92847"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=92847"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=92847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}