{"id":92348,"date":"2019-02-03T19:53:24","date_gmt":"2019-02-03T18:53:24","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/basta-una-volta-smeeton-m-9788842525745\/"},"modified":"2026-05-09T02:00:33","modified_gmt":"2026-05-09T00:00:33","slug":"basta-una-volta-smeeton-m-9788842525745","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/","title":{"rendered":"basta una volta"},"content":{"rendered":"<p>Questo &egrave; il diario della lotta sostenuta, agli estremi limiti delle possibilit&agrave; umane, da persone eccezionali durante due successivi tentativi di doppiare Capo Horn: quando una tremenda ondata capovolge&nbsp;il ketch di 14 metri&nbsp;&#8220;Tzu-Hang&#8221;, riducendolo a un relitto e costringendo l&#8217;equipaggio a sforzi sovrumani per raggiungere un rifugio in Cile, ripartire per lo stesso viaggio dopo un anno passato a riparare la barca diventa un imperativo, una sfida con se stessi e con il mare.<\/p>\n<p>Edizione: 1999<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la terribile avventura dello &#8216;tzu-hang&#8217;<\/p>\n<p class=\"autore\"><span>Author: <\/span>smeeton m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842525745<\/p>\n","protected":false},"featured_media":141673,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805],"product_tag":[],"class_list":{"0":"post-92348","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>basta una volta - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"basta una volta\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la terribile avventura dello &#039;tzu-hang&#039;Author: smeeton m.Publisher: Ugo Mursia EditoreISBN: 9788842525745\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"403\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/\",\"name\":\"basta una volta - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bastaunavolta-mursia-2.jpg\",\"datePublished\":\"2019-02-03T18:53:24+00:00\",\"dateModified\":\"2026-05-09T00:00:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bastaunavolta-mursia-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bastaunavolta-mursia-2.jpg\",\"width\":403,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/basta-una-volta-smeeton-m-9788842525745\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"basta una volta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842525745\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"basta una volta - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/","og_locale":"en_US","og_type":"article","og_title":"basta una volta","og_description":"Subtitle: la terribile avventura dello 'tzu-hang'Author: smeeton m.Publisher: Ugo Mursia EditoreISBN: 9788842525745","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:00:33+00:00","og_image":[{"width":403,"height":595,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/","name":"basta una volta - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2.jpg","datePublished":"2019-02-03T18:53:24+00:00","dateModified":"2026-05-09T00:00:33+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2.jpg","width":403,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/basta-una-volta-smeeton-m-9788842525745\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"basta una volta"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788842525745","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bastaunavolta-mursia-2-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/92348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=92348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/141673"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=92348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=92348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=92348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=92348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}