{"id":91794,"date":"2019-02-03T19:57:40","date_gmt":"2019-02-03T18:57:40","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/"},"modified":"2026-07-11T02:49:39","modified_gmt":"2026-07-11T00:49:39","slug":"loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/","title":{"rendered":"loisirs nautiques hors-serie 34"},"content":{"rendered":"<p>Les Hors-S&eacute;rie de &#8220;Loisirs Nautiques&#8221; sont un vaste rendez-vous de conceptions, de donn&eacute;es sur l&#8217;architecture et la construction navales amateurs et professionnels, mais aussi de la navigation, du bricolage &agrave; bord, des astuces et, enfin, de l&#8217;aboutissement au reve longtemps muri des grands voyages &agrave; travers les oc&eacute;ans&#8230;<\/p>\n<p>Edition: 2000<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>guide des voiliers d&#8217;occasion de 5 a 9 metres<\/p>\n<p class=\"autore\"><span>Author: <\/span>van deth e.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>loisirs nautiques<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>3792753120001<\/p>\n","protected":false},"featured_media":127613,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2767,2593],"product_tag":[],"class_list":{"0":"post-91794","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-buying-a-boat","7":"product_cat-magazines","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>loisirs nautiques hors-serie 34 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"loisirs nautiques hors-serie 34\" \/>\n<meta property=\"og:description\" content=\"Subtitle: guide des voiliers d&#039;occasion de 5 a 9 metresAuthor: van deth e.Publisher: loisirs nautiquesISBN: 3792753120001\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T00:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"610\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/\",\"name\":\"loisirs nautiques hors-serie 34 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/loisirsnautiqueshs34-2.jpg\",\"datePublished\":\"2019-02-03T18:57:40+00:00\",\"dateModified\":\"2026-07-11T00:49:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/loisirsnautiqueshs34-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/loisirsnautiqueshs34-2.jpg\",\"width\":610,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"loisirs nautiques hors-serie 34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"3792753120001\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"loisirs nautiques hors-serie 34 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/","og_locale":"en_US","og_type":"article","og_title":"loisirs nautiques hors-serie 34","og_description":"Subtitle: guide des voiliers d'occasion de 5 a 9 metresAuthor: van deth e.Publisher: loisirs nautiquesISBN: 3792753120001","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T00:49:39+00:00","og_image":[{"width":610,"height":601,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/","name":"loisirs nautiques hors-serie 34 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2.jpg","datePublished":"2019-02-03T18:57:40+00:00","dateModified":"2026-07-11T00:49:39+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2.jpg","width":610,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/loisirs-nautiques-hors-serie-34-van-deth-e-3792753120001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"loisirs nautiques hors-serie 34"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"3792753120001","product_condition":"new"},"df_price":17,"df_sale_price":17,"df_regular_price":25,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/loisirsnautiqueshs34-2-300x296.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/91794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=91794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127613"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=91794"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=91794"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=91794"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=91794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}