{"id":90735,"date":"2019-02-03T19:35:15","date_gmt":"2019-02-03T18:35:15","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/"},"modified":"2026-05-09T02:30:13","modified_gmt":"2026-05-09T00:30:13","slug":"avventure-del-capitano-de-contreras-de-contreras-a-9788830450509","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/","title":{"rendered":"avventure del capitano de contreras"},"content":{"rendered":"<p>&Egrave; il 1630 quando il Capitano Alonso de Contreras affida alla carta e all&rsquo;inchiostro le proprie memorie militaresche (e umane), come fecero del resto molti tra i soldati spagnoli di fanteria dell&rsquo;epoca all&rsquo;approssimarsi del tramonto dell&rsquo;esistenza, chi per ottenere favori o riconoscimenti, chi per vanagloria o nella speranza di lasciare una traccia di s&eacute; ai posteri. Tutti o quasi accomunati da una scrittura onesta e sobria, da un lato ereditata dall&rsquo;abitudine al resoconto asciutto, tipica di soldati e veterani qual &egrave; Contreras, dall&rsquo;altro per lo scarso, se non inesistente, bagaglio culturale dell&rsquo;autore, che ne diventa paradossalmente il punto di forza. &#8220;Sono proprio l&rsquo;assenza di ambizioni letterarie, la goffaggine narrativa, l&rsquo;ingenuit&agrave; tecnica a rendere cos&igrave; singolari quei racconti. Che, quanto ad esattezza priva di erudizione, naturalezza elementare, efficace e disinibita alta capacit&agrave; descrittiva, superano la scrittura di mestiere trasformando ogni testimonianza in una miniera d&rsquo;oro&#8221;, come sottolinea l&rsquo;autore della prefazione. Disseppellita dall&rsquo;oblio dopo tre secoli, infatti, l&rsquo;autobiografia di De Contreras conquista la cr&egrave;me degli intellettuali europei di inizio Novecento, da Jos&eacute; Ortega y Gasset a Sciascia, approdando sulla scrivania di Leo Longanesi negli Anni&nbsp;Quaranta e ispirando, mezzo secolo dopo, ad Arturo P&eacute;rez-Reverte il personaggio del Capitano Alatriste. Tra i suoi punti di forza, il linguaggio vero, amalgama di un parlato e della lingua franca che risuonava nei porti del Mediterraneo dell&rsquo;epoca, la sua sincerit&agrave;, la memoria strabiliante e&nbsp;lo slancio narrativo che mai si sovrappone alla verit&agrave; e che lo rende incredibilmente moderno e attuale.<\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>de contreras a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>longanesi <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788830450509<\/p>\n","protected":false},"featured_media":130800,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,3042],"product_tag":[],"class_list":{"0":"post-90735","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-narrative-modern-era","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>avventure del capitano de contreras - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"avventure del capitano de contreras\" \/>\n<meta property=\"og:description\" content=\"Author: de contreras a.Publisher: longanesi ISBN: 9788830450509\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,60\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/\",\"name\":\"avventure del capitano de contreras - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventuredelcapitanodecontreras-decontreras-3.jpg\",\"datePublished\":\"2019-02-03T18:35:15+00:00\",\"dateModified\":\"2026-05-09T00:30:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventuredelcapitanodecontreras-decontreras-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventuredelcapitanodecontreras-decontreras-3.jpg\",\"width\":300,\"height\":444},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"avventure del capitano de contreras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.60\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788830450509\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"avventure del capitano de contreras - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/","og_locale":"en_US","og_type":"article","og_title":"avventure del capitano de contreras","og_description":"Author: de contreras a.Publisher: longanesi ISBN: 9788830450509","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:30:13+00:00","og_image":[{"width":300,"height":444,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,60","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/","name":"avventure del capitano de contreras - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3.jpg","datePublished":"2019-02-03T18:35:15+00:00","dateModified":"2026-05-09T00:30:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3.jpg","width":300,"height":444},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/avventure-del-capitano-de-contreras-de-contreras-a-9788830450509\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"avventure del capitano de contreras"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.60","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788830450509","product_condition":"new"},"df_price":18.6,"df_sale_price":"","df_regular_price":18.6,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventuredelcapitanodecontreras-decontreras-3-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/90735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=90735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/130800"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=90735"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=90735"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=90735"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=90735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}