{"id":90366,"date":"2019-02-03T19:37:50","date_gmt":"2019-02-03T18:37:50","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/"},"modified":"2026-05-09T02:25:46","modified_gmt":"2026-05-09T00:25:46","slug":"quaderno-appunti-di-bordo-aa-vv-9788885719033","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/","title":{"rendered":"quaderno &#8220;appunti di bordo&#8221;"},"content":{"rendered":"<p>Un pratico bloc-notes per scrivere i propri appunti di bordo su pagine quadrettate. All&#8217;interno sono riportati su ogni pagina detti e proverbi marinari. Il bloc-notes comprende un inserto che riporta in belle mappe a colori la cartografia completa edita dall&rsquo;Istituto Idrografico della Marina Militare Italiana. Un modo simpatico per tenere ordinati i propri appunti nautici, il promemoria dei lavori da eseguire alla propria barca, annotazioni di crociera e di viaggio, incontri in mare&#8230;<\/p>\n<p>Edizione: 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>con i proverbi marinari<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Edizioni Il Frangente<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788885719033<\/p>\n","protected":false},"featured_media":150364,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2943],"product_tag":[],"class_list":{"0":"post-90366","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-notebooks","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>quaderno &quot;appunti di bordo&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"quaderno &quot;appunti di bordo&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: con i proverbi marinariAuthor: aa.vv.Manufacturer: Edizioni Il FrangenteISBN: 9788885719033\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;8,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/\",\"name\":\"quaderno \\\"appunti di bordo\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg\",\"datePublished\":\"2019-02-03T18:37:50+00:00\",\"dateModified\":\"2026-05-09T00:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg\",\"width\":515,\"height\":723},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quaderno-appunti-di-bordo-aa-vv-9788885719033\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"quaderno &#8220;appunti di bordo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"8.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788885719033\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"quaderno \"appunti di bordo\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/","og_locale":"en_US","og_type":"article","og_title":"quaderno \"appunti di bordo\"","og_description":"Subtitle: con i proverbi marinariAuthor: aa.vv.Manufacturer: Edizioni Il FrangenteISBN: 9788885719033","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:25:46+00:00","og_image":[{"width":515,"height":723,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;8,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/","name":"quaderno \"appunti di bordo\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg","datePublished":"2019-02-03T18:37:50+00:00","dateModified":"2026-05-09T00:25:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2.jpg","width":515,"height":723},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quaderno-appunti-di-bordo-aa-vv-9788885719033\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"quaderno &#8220;appunti di bordo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"8.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788885719033","product_condition":"new"},"df_price":8,"df_sale_price":"","df_regular_price":8,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appunti-di-bordo-con-proverbi-marinari-frangente-2-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/90366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=90366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/150364"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=90366"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=90366"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=90366"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=90366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}