{"id":90365,"date":"2019-02-03T19:37:50","date_gmt":"2019-02-03T18:37:50","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-pilot-charts-di-tutti-gli-oceani-cornell-j-i-9780955639685\/"},"modified":"2026-05-09T02:25:46","modified_gmt":"2026-05-09T00:25:46","slug":"le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/","title":{"rendered":"le pilot charts di tutti gli oceani"},"content":{"rendered":"<p>Atlante che racchiude 60 pilot charts mensili per tutti gli oceani, con informazioni su venti, correnti, tempeste e zone di alta pressione.<\/p>\n<p>Cm 44&#215;30<\/p>\n<p>Edizione: 2011<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>jimmy cornell &#8211; ivan cornell<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>cornell sailing<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9780955639685<\/p>\n","protected":false},"featured_media":103171,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2459],"product_tag":[],"class_list":{"0":"post-90365","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-atlases-kits-and-collections","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le pilot charts di tutti gli oceani - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le pilot charts di tutti gli oceani\" \/>\n<meta property=\"og:description\" content=\"Author: jimmy cornell - ivan cornellManufacturer: cornell sailingISBN: 9780955639685\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"252\" \/>\n\t<meta property=\"og:image:height\" content=\"178\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;69,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/\",\"name\":\"le pilot charts di tutti gli oceani - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pilotchartstuttioceani-2.jpg\",\"datePublished\":\"2019-02-03T18:37:50+00:00\",\"dateModified\":\"2026-05-09T00:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pilotchartstuttioceani-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pilotchartstuttioceani-2.jpg\",\"width\":252,\"height\":178},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le pilot charts di tutti gli oceani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"69.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9780955639685\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le pilot charts di tutti gli oceani - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/","og_locale":"en_US","og_type":"article","og_title":"le pilot charts di tutti gli oceani","og_description":"Author: jimmy cornell - ivan cornellManufacturer: cornell sailingISBN: 9780955639685","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:25:46+00:00","og_image":[{"width":252,"height":178,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;69,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/","name":"le pilot charts di tutti gli oceani - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg","datePublished":"2019-02-03T18:37:50+00:00","dateModified":"2026-05-09T00:25:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg","width":252,"height":178},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-pilot-charts-di-tutti-gli-oceani-jimmy-cornell-ivan-cornell-9780955639685\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le pilot charts di tutti gli oceani"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"69.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9780955639685","product_condition":"new"},"df_price":69,"df_sale_price":"","df_regular_price":69,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pilotchartstuttioceani-2.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/90365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=90365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/103171"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=90365"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=90365"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=90365"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=90365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}