{"id":89947,"date":"2019-02-03T19:40:23","date_gmt":"2019-02-03T18:40:23","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/e-poi-il-silenzio-mazzari-p-9788856752670\/"},"modified":"2026-07-11T03:30:59","modified_gmt":"2026-07-11T01:30:59","slug":"e-poi-il-silenzio-mazzari-p-9788856752670","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/","title":{"rendered":"e poi il silenzio"},"content":{"rendered":"<p>Pietro Raimondi &egrave; un giovane ingegnere molto ambizioso che, in un solo decennio, a cavallo tra gli anni Sessanta e Settanta, conquista il mercato delle navi da diporto contribuendo alla crescita economica nazionale. In queste pagine si racconta una parte di storia della nautica e soprattutto la forza inesauribile di una passione, quella per il mare, che oggi come ieri accende l&#8217;animo di moltissime persone. Cos&igrave; la storia di Pietro &egrave; la storia di un&#8217;Italia &#8220;marina&#8221;, dei suoi litorali pi&ugrave; belli, dei cantieri navali e dei suoi personaggi illustri. E&#8217; il racconto di un animo inquieto, che guarda sempre in avanti, e che dedica le sue migliori energie alla crescita professionale e all&#8217;amore per il mare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>mazzari p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>gruppo albatros il filo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788856752670<\/p>\n","protected":false},"featured_media":139783,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3007],"product_tag":[],"class_list":{"0":"post-89947","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-monographs","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>e poi il silenzio - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"e poi il silenzio\" \/>\n<meta property=\"og:description\" content=\"Author: mazzari p.Publisher: gruppo albatros il filoISBN: 9788856752670\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:30:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"388\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/\",\"name\":\"e poi il silenzio - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/epoiilsilenzio-5.jpg\",\"datePublished\":\"2019-02-03T18:40:23+00:00\",\"dateModified\":\"2026-07-11T01:30:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/epoiilsilenzio-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/epoiilsilenzio-5.jpg\",\"width\":388,\"height\":589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/e-poi-il-silenzio-mazzari-p-9788856752670\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"e poi il silenzio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788856752670\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"e poi il silenzio - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/","og_locale":"en_US","og_type":"article","og_title":"e poi il silenzio","og_description":"Author: mazzari p.Publisher: gruppo albatros il filoISBN: 9788856752670","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:30:59+00:00","og_image":[{"width":388,"height":589,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/","name":"e poi il silenzio - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5.jpg","datePublished":"2019-02-03T18:40:23+00:00","dateModified":"2026-07-11T01:30:59+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5.jpg","width":388,"height":589},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/e-poi-il-silenzio-mazzari-p-9788856752670\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"e poi il silenzio"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788856752670","product_condition":"new"},"df_price":19.9,"df_sale_price":"","df_regular_price":19.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/epoiilsilenzio-5-198x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/89947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=89947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/139783"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=89947"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=89947"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=89947"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=89947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}