{"id":89934,"date":"2019-02-03T19:40:35","date_gmt":"2019-02-03T18:40:35","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/"},"modified":"2026-07-11T03:30:46","modified_gmt":"2026-07-11T01:30:46","slug":"navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/","title":{"rendered":"navigare il lago di como &#8211; sailing on lake como"},"content":{"rendered":"<p>Splendido libro storico e fotografico sul Lago di Como,&nbsp;la sua flotta, i suoi porti, il suo paesaggio, le feste, i musei e l&#8217;ospitalit&agrave;.<\/p>\n<p>Lingue: Italiano e Inglese<\/p>\n<p>Edizione: 2018<\/p>\n<p>Historical and photographic book about Lake Como, its fleet, its ports, its landscape, holidays, museums and hospitality.<\/p>\n<p>Languages: English and Italian<\/p>\n<p>Edition: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>i porti e il paesaggio, la flotta, le feste, i musei, l&#8217;ospitalit\u00e0 &#8211; ports and the landscape, fleet, holidays, museums, hospitality<\/p>\n<p class=\"autore\"><span>Author: <\/span>fontana c.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>attilio sampietro edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788887672527<\/p>\n","protected":false},"featured_media":135512,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2596,3059,3110,2741],"product_tag":[],"class_list":{"0":"post-89934","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-architecture-design-and-lifestyle","7":"product_cat-essays-books-navigation-history-passenger-ships","8":"product_cat-everything-else-italy-picture-books-tourism","9":"product_cat-navigation-history","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>navigare il lago di como - sailing on lake como - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"navigare il lago di como - sailing on lake como\" \/>\n<meta property=\"og:description\" content=\"Subtitle: i porti e il paesaggio, la flotta, le feste, i musei, l&#039;ospitalit\u00e0 - ports and the landscape, fleet, holidays, museums, hospitalityAuthor: fontana c.Publisher: attilio sampietro edizioniISBN: 9788887672527\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:30:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;39,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/\",\"name\":\"navigare il lago di como - sailing on lake como - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigareillagodicomo-sailingonlakecomo-4.jpg\",\"datePublished\":\"2019-02-03T18:40:35+00:00\",\"dateModified\":\"2026-07-11T01:30:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigareillagodicomo-sailingonlakecomo-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigareillagodicomo-sailingonlakecomo-4.jpg\",\"width\":800,\"height\":565},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"navigare il lago di como &#8211; sailing on lake como\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"39.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788887672527\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"navigare il lago di como - sailing on lake como - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/","og_locale":"en_US","og_type":"article","og_title":"navigare il lago di como - sailing on lake como","og_description":"Subtitle: i porti e il paesaggio, la flotta, le feste, i musei, l'ospitalit\u00e0 - ports and the landscape, fleet, holidays, museums, hospitalityAuthor: fontana c.Publisher: attilio sampietro edizioniISBN: 9788887672527","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:30:46+00:00","og_image":[{"width":800,"height":565,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;39,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/","name":"navigare il lago di como - sailing on lake como - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4.jpg","datePublished":"2019-02-03T18:40:35+00:00","dateModified":"2026-07-11T01:30:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4.jpg","width":800,"height":565},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigare-il-lago-di-como-sailing-on-lake-como-fontana-c-9788887672527\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"navigare il lago di como &#8211; sailing on lake como"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"39.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788887672527","product_condition":"new"},"df_price":39,"df_sale_price":"","df_regular_price":39,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigareillagodicomo-sailingonlakecomo-4-300x212.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/89934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=89934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135512"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=89934"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=89934"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=89934"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=89934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}