{"id":89664,"date":"2019-02-03T19:42:27","date_gmt":"2019-02-03T18:42:27","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/eroe-non-soltanto-per-l-italia-ma-per-l-umanit-bianchi-g-19048838324370\/"},"modified":"2026-05-09T02:17:41","modified_gmt":"2026-05-09T00:17:41","slug":"i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/","title":{"rendered":"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro"},"content":{"rendered":"<p>Descrizione del <strong>salvataggio di Todaro dei naufraghi del <em>Kabalo<\/em><\/strong> tratte dal volume <em>Les Belges du Kabalo<\/em>, corredato da <strong>numerose fotografie<\/strong> in b\/n. Un&rsquo;impresa di salvataggio destinata a entrare nella storia. Dopo un giorno di navigazione, per poter procedere pi&ugrave; velocemente, Todaro <strong>prende a bordo tutti e ventisei i marinai del mercantile<\/strong>, stipandoli nella falsatorre del battello, e prosegue verso Nord, in direzione dell&rsquo;arcipelago portoghese delle<strong> Azzorre<\/strong>, dove arriva all&rsquo;alba del 19 ottobre nella pressoch&eacute; deserta cala di Santa Maria. Al momento dello sbarco, a nome di tutti, il tenente Caudron, ringraziando il comandante italiano, chiede di poter conoscere il suo nome. Todaro, persona di innata modestia, risponde di chiamarsi Salvatore Bruno (i suoi due nomi di battesimo), tacendo il cognome.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>pierre goemaere &#8211; gianni bianchi<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>associazione culturale sarasota<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>19048838324370<\/p>\n","protected":false},"featured_media":131608,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,3051],"product_tag":[],"class_list":{"0":"post-89664","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-from-1919-to-1945","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i naufraghi del kabalo raccontano il salvataggio di salvatore todaro - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro\" \/>\n<meta property=\"og:description\" content=\"Author: pierre goemaere - gianni bianchiPublisher: associazione culturale sarasotaISBN: 19048838324370\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;26,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/\",\"name\":\"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg\",\"datePublished\":\"2019-02-03T18:42:27+00:00\",\"dateModified\":\"2026-05-09T00:17:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg\",\"width\":1600,\"height\":1554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"26.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"19048838324370\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/","og_locale":"en_US","og_type":"article","og_title":"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro","og_description":"Author: pierre goemaere - gianni bianchiPublisher: associazione culturale sarasotaISBN: 19048838324370","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:17:41+00:00","og_image":[{"width":1600,"height":1554,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;26,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/","name":"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg","datePublished":"2019-02-03T18:42:27+00:00","dateModified":"2026-05-09T00:17:41+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3.jpg","width":1600,"height":1554},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-19048838324370\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i naufraghi del kabalo raccontano il salvataggio di salvatore todaro"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"26.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"19048838324370","product_condition":"new"},"df_price":26,"df_sale_price":"","df_regular_price":26,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/i-naufraghi-del-kabalo-raccontano-il-salvataggio-di-salvatore-todaro-pierre-goemaere-gianni-bianchi-sarasota-3-300x291.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/89664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=89664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/131608"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=89664"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=89664"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=89664"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=89664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}