{"id":89472,"date":"2026-05-14T18:00:43","date_gmt":"2026-05-14T16:00:43","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/manuale-nautico-illustrato-dedekam-i-9788885986459\/"},"modified":"2026-07-11T03:22:40","modified_gmt":"2026-07-11T01:22:40","slug":"navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/","title":{"rendered":"NAVIGAZIONE | Tradizionale &#8211; Elettronica &#8211; Astronomica"},"content":{"rendered":"<p>Un <strong>manuale magistralmente illustrato dall&rsquo;autore<\/strong> stesso che, in modo chiaro ed essenziale, espone i <strong>concetti fondamentali<\/strong> della navigazione tradizionale, elettronica e astronomica.&nbsp;La conoscenza della navigazione tradizionale e\u0300 la premessa necessaria per comprendere e utilizzare al meglio le moderne strumentazioni elettroniche, oggi sempre piu\u0300 presenti anche a bordo di piccole imbarcazioni da diporto.<\/p>\n<p>Attraverso <strong>diagrammi di facile comprensione<\/strong> e <strong>oltre un centinaio di illustrazioni <\/strong>di grande efficacia didattica vengono spiegati strumenti e tecniche di carteggio, uso del GPS e del radar, sistema AIS e i principi della navigazione astronomica con il sestante per l&rsquo;osservazione del Sole al meridiano, la determinazione della latitudine con la Polare e l&rsquo;utilizzo delle stelle per il punto nave. <strong>Testi compatti e chiaramente informativi<\/strong> accompagnano il ricco apparato iconografico, rendendo i concetti immediatamente assimilabili.<\/p>\n<p>Un <strong>manuale facilmente consultabile<\/strong>, adatto sia ai neofiti che intendono apprendere le basi della navigazione, sia ai piu\u0300 esperti che vogliono avere sempre sottomano i parametri indispensabili per una navigazione sicura e consapevole.<\/p>\n<p>Edizione: 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>Manuale illustrato<\/p>\n<p class=\"autore\"><span>Author: <\/span>Ivar Dedekam<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Edizioni il Frangente<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836103133<\/p>\n","protected":false},"featured_media":167365,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2987,2579,2679],"product_tag":[],"class_list":{"0":"post-89472","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-boat-license","7":"product_cat-books-celestial-and-traditional-navigation-and-astronomy","8":"product_cat-electronics","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NAVIGAZIONE | Tradizionale - Elettronica - Astronomica - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NAVIGAZIONE | Tradizionale - Elettronica - Astronomica\" \/>\n<meta property=\"og:description\" content=\"Subtitle: Manuale illustratoAuthor: Ivar DedekamPublisher: Edizioni il FrangenteISBN: 9788836103133\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:22:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/\",\"name\":\"NAVIGAZIONE | Tradizionale - Elettronica - Astronomica - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigazione-dedekam-3.jpg\",\"datePublished\":\"2026-05-14T16:00:43+00:00\",\"dateModified\":\"2026-07-11T01:22:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigazione-dedekam-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navigazione-dedekam-3.jpg\",\"width\":500,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NAVIGAZIONE | Tradizionale &#8211; Elettronica &#8211; Astronomica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836103133\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NAVIGAZIONE | Tradizionale - Elettronica - Astronomica - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/","og_locale":"en_US","og_type":"article","og_title":"NAVIGAZIONE | Tradizionale - Elettronica - Astronomica","og_description":"Subtitle: Manuale illustratoAuthor: Ivar DedekamPublisher: Edizioni il FrangenteISBN: 9788836103133","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:22:40+00:00","og_image":[{"width":500,"height":703,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/","name":"NAVIGAZIONE | Tradizionale - Elettronica - Astronomica - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3.jpg","datePublished":"2026-05-14T16:00:43+00:00","dateModified":"2026-07-11T01:22:40+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3.jpg","width":500,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navigazione-tradizionale-elettronica-astronomica-ivar-dedekam-9788836103133\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"NAVIGAZIONE | Tradizionale &#8211; Elettronica &#8211; Astronomica"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788836103133","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navigazione-dedekam-3-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/89472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=89472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/167365"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=89472"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=89472"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=89472"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=89472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}