{"id":89212,"date":"2019-02-03T19:45:44","date_gmt":"2019-02-03T18:45:44","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/"},"modified":"2026-05-09T02:12:37","modified_gmt":"2026-05-09T00:12:37","slug":"dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/","title":{"rendered":"dozier&#8217;s waterway guide southern 2010"},"content":{"rendered":"<p>Updated annually, &#8220;Dozier&#8217;s Waterway Guide Southern 2010&#8221; is the indispensable cruising companion for boaters exploring Florida&rsquo;s East coast, the St. John&rsquo;s River, the Okeechobee Waterway, the Keys, Florida&rsquo;s West coast and the Gulf of Mexico to Brownsville, Texas. The guide features over 500 pages of mile-by-mile navigation information, aerial photography with marked routes, marina listings and locator charts, anchorage information and expanded &#8220;Goin&rsquo; Ashore&#8221; articles on ports along the way. Helpful cruising data like GPS waypoints, detailed planning maps, distance tables and bridge tables helps get cruisers there safely. Flexible spiral binding and heavy laminated covers with bookmarker flaps ensure durability and easy use in the cockpit and at the helm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>florida, the keys and the gulf coast<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>waterway guide media<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9780982488928<\/p>\n","protected":false},"featured_media":101509,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2723],"product_tag":[],"class_list":{"0":"post-89212","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-north-and-south-america","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dozier&#039;s waterway guide southern 2010 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dozier&#039;s waterway guide southern 2010\" \/>\n<meta property=\"og:description\" content=\"Subtitle: florida, the keys and the gulf coastAuthor: aa.vv.Publisher: waterway guide mediaISBN: 9780982488928\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:12:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"425\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;37,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/\",\"name\":\"dozier's waterway guide southern 2010 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dozierswaterwayguidesouthern2010-4.jpg\",\"datePublished\":\"2019-02-03T18:45:44+00:00\",\"dateModified\":\"2026-05-09T00:12:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dozierswaterwayguidesouthern2010-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dozierswaterwayguidesouthern2010-4.jpg\",\"width\":425,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dozier&#8217;s waterway guide southern 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"37.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9780982488928\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dozier's waterway guide southern 2010 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/","og_locale":"en_US","og_type":"article","og_title":"dozier's waterway guide southern 2010","og_description":"Subtitle: florida, the keys and the gulf coastAuthor: aa.vv.Publisher: waterway guide mediaISBN: 9780982488928","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:12:37+00:00","og_image":[{"width":425,"height":500,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;37,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/","name":"dozier's waterway guide southern 2010 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4.jpg","datePublished":"2019-02-03T18:45:44+00:00","dateModified":"2026-05-09T00:12:37+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4.jpg","width":425,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dozier-s-waterway-guide-southern-2010-aa-vv-9780982488928\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dozier&#8217;s waterway guide southern 2010"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"37.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9780982488928","product_condition":"new"},"df_price":37,"df_sale_price":37,"df_regular_price":54,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dozierswaterwayguidesouthern2010-4-255x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/89212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=89212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/101509"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=89212"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=89212"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=89212"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=89212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}