{"id":88947,"date":"2019-02-03T19:26:00","date_gmt":"2019-02-03T18:26:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/"},"modified":"2026-05-09T02:47:33","modified_gmt":"2026-05-09T00:47:33","slug":"la-balena-della-tempesta-box-puzzle-davies-b-9788859247302","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/","title":{"rendered":"la balena della tempesta &#8211; box puzzle"},"content":{"rendered":"<p>La storia dell&#8217;amicizia tra Nico e la piccola balena in un nuovo formato: una comoda valigetta con una versione mini del libro e sei cubetti con altrettante illustrazioni del volume da ricomporre.<\/p>\n<p>Et&agrave; di lettura: 4+<\/p>\n<p>Edizione: 2018<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>davies b.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Giralangolo (EDT)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788859247302<\/p>\n","protected":false},"featured_media":124284,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2937,2614],"product_tag":[],"class_list":{"0":"post-88947","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-children","7":"product_cat-illustrated-books-and-fiction","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la balena della tempesta - box puzzle - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la balena della tempesta - box puzzle\" \/>\n<meta property=\"og:description\" content=\"Author: davies b.Publisher: Giralangolo (EDT)ISBN: 9788859247302\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/\",\"name\":\"la balena della tempesta - box puzzle - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/balenadellatempestaboxpuzzle-davies-5.jpg\",\"datePublished\":\"2019-02-03T18:26:00+00:00\",\"dateModified\":\"2026-05-09T00:47:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/balenadellatempestaboxpuzzle-davies-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/balenadellatempestaboxpuzzle-davies-5.jpg\",\"width\":600,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la balena della tempesta &#8211; box puzzle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788859247302\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la balena della tempesta - box puzzle - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/","og_locale":"en_US","og_type":"article","og_title":"la balena della tempesta - box puzzle","og_description":"Author: davies b.Publisher: Giralangolo (EDT)ISBN: 9788859247302","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:47:33+00:00","og_image":[{"width":600,"height":534,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/","name":"la balena della tempesta - box puzzle - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5.jpg","datePublished":"2019-02-03T18:26:00+00:00","dateModified":"2026-05-09T00:47:33+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5.jpg","width":600,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-balena-della-tempesta-box-puzzle-davies-b-9788859247302\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la balena della tempesta &#8211; box puzzle"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788859247302","product_condition":"new"},"df_price":22.5,"df_sale_price":"","df_regular_price":22.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/balenadellatempestaboxpuzzle-davies-5-300x267.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/88947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=88947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/124284"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=88947"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=88947"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=88947"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=88947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}