{"id":88871,"date":"2019-02-03T19:26:37","date_gmt":"2019-02-03T18:26:37","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/"},"modified":"2026-07-11T04:10:28","modified_gmt":"2026-07-11T02:10:28","slug":"windsurfmania-e-metodo-segnana-m-negri-h-961953163","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/","title":{"rendered":"windsurfmania&#8230; e metodo"},"content":{"rendered":"<p>Gli autori&nbsp;mettono a disposizione del lettore la loro esperienza e professionalit&agrave; con&nbsp;questo manuale pratico, di facile consultazione, ricco di foto e di validi consigli per quel che riguarda la tecnica e la didattica del windsurf, il fitness e l&#8217;alimentazione appropriata.<\/p>\n<p>Costo del libro &euro; 22,00 + &euro; 7,00 per la consegna in libreria<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>segnana m.  negri h.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>surfsegnana<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>961953163<\/p>\n","protected":false},"featured_media":133829,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3079],"product_tag":[],"class_list":{"0":"post-88871","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitesurf-sup-and-windsurf","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>windsurfmania... e metodo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"windsurfmania... e metodo\" \/>\n<meta property=\"og:description\" content=\"Author: segnana m. negri h.Publisher: surfsegnanaISBN: 961953163\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:10:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;30,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/\",\"name\":\"windsurfmania... e metodo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/windsurfmaniaemetodo3-4.jpg\",\"datePublished\":\"2019-02-03T18:26:37+00:00\",\"dateModified\":\"2026-07-11T02:10:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/windsurfmaniaemetodo3-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/windsurfmaniaemetodo3-4.jpg\",\"width\":435,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"windsurfmania&#8230; e metodo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"961953163\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"windsurfmania... e metodo - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/","og_locale":"en_US","og_type":"article","og_title":"windsurfmania... e metodo","og_description":"Author: segnana m. negri h.Publisher: surfsegnanaISBN: 961953163","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:10:28+00:00","og_image":[{"width":435,"height":607,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;30,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/","name":"windsurfmania... e metodo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4.jpg","datePublished":"2019-02-03T18:26:37+00:00","dateModified":"2026-07-11T02:10:28+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4.jpg","width":435,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/windsurfmania-e-metodo-segnana-m-negri-h-961953163\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"windsurfmania&#8230; e metodo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"961953163","product_condition":"new"},"df_price":30,"df_sale_price":"","df_regular_price":30,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/windsurfmaniaemetodo3-4-215x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/88871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=88871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/133829"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=88871"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=88871"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=88871"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=88871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}