{"id":88853,"date":"2019-02-03T19:26:40","date_gmt":"2019-02-03T18:26:40","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/"},"modified":"2026-07-11T04:10:08","modified_gmt":"2026-07-11T02:10:08","slug":"charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/","title":{"rendered":"charles e. nicholson and his yachts"},"content":{"rendered":"<p>This magnificent book is a celebration of the work of Charles E. Nicholson, the most important British yacht designer of the Twentieth Century. The stunning photos of internationally renowned Italian photographer Franco Pace, capture the grace and elegance of these well known yachts sailing and racing today.&nbsp; In a fascinating preface, yacht historian William Collier chronicles the development of Nicholson&#8217;s designs from the 1890s to the start of the Second World War.&nbsp; Together they have combined a gloriously lavish tribute to the scion of the Nicholson family, which will be of enduring interest.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>collier w.  pace f.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Adlard Coles Nautical (Bloomsbury Publishing)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9780713657364<\/p>\n","protected":false},"featured_media":127535,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3007,2576],"product_tag":[],"class_list":{"0":"post-88853","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monographs","7":"product_cat-books-navigation-illustrated-books","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>charles e. nicholson and his yachts - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"charles e. nicholson and his yachts\" \/>\n<meta property=\"og:description\" content=\"Author: collier w. pace f.Publisher: Adlard Coles Nautical (Bloomsbury Publishing)ISBN: 9780713657364\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:10:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;100,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/\",\"name\":\"charles e. nicholson and his yachts - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/charlesenicholson-3.jpg\",\"datePublished\":\"2019-02-03T18:26:40+00:00\",\"dateModified\":\"2026-07-11T02:10:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/charlesenicholson-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/charlesenicholson-3.jpg\",\"width\":420,\"height\":573},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"charles e. nicholson and his yachts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"100.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9780713657364\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"charles e. nicholson and his yachts - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/","og_locale":"en_US","og_type":"article","og_title":"charles e. nicholson and his yachts","og_description":"Author: collier w. pace f.Publisher: Adlard Coles Nautical (Bloomsbury Publishing)ISBN: 9780713657364","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:10:08+00:00","og_image":[{"width":420,"height":573,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;100,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/","name":"charles e. nicholson and his yachts - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3.jpg","datePublished":"2019-02-03T18:26:40+00:00","dateModified":"2026-07-11T02:10:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3.jpg","width":420,"height":573},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/charles-e-nicholson-and-his-yachts-collier-w-pace-f-9780713657364\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"charles e. nicholson and his yachts"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"100.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9780713657364","product_condition":"new"},"df_price":100,"df_sale_price":"","df_regular_price":100,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/charlesenicholson-3-220x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/88853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=88853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127535"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=88853"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=88853"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=88853"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=88853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}