{"id":88046,"date":"2022-02-02T15:00:41","date_gmt":"2022-02-02T14:00:41","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/nel-blu-giovanni-soldini-9788850262342\/"},"modified":"2026-05-09T02:36:49","modified_gmt":"2026-05-09T00:36:49","slug":"nel-blu-giovanni-soldini-9788850262342","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/","title":{"rendered":"nel blu"},"content":{"rendered":"<p><em>&laquo;La barca a vela per me ha sempre rappresentato un modo per viaggiare. L&#8217;idea di poter andare da un posto all&#8217;altro utilizzando solo l&#8217;energia della natura mi ha sempre affascinato.&raquo;<\/em><\/p>\n<p>Con queste parole il celebre navigatore solitario comincia il racconto del proprio amore per la vela, dalle esperienze compiute da bambino sul Lago Maggiore in compagnia del padre agli esordi nelle competizioni, sino alle regate d&#8217;altura e alla prima delle ormai numerose traversate oceaniche compiute finora. Un&#8217;avventura&nbsp;&ndash; una metafora della vita&nbsp;&ndash; fatta di impegno e disciplina, sofferenza e dolori, ma anche di gioie ed emozioni. Un racconto vivido, in cui il mare&nbsp;&ndash; anzitutto il rispetto per il mare, perch&eacute; la natura &egrave; sempre pi&ugrave; forte di noi&nbsp;&ndash;, oltre che una scelta e una lezione di vita, &egrave; un modo per conoscersi e mettersi alla prova e un&#8217;occasione per scoprire altri luoghi, altre culture, conoscere nuovi amici e continuare a inseguire i proprio sogni.&nbsp;<\/p>\n<p>Appendici di Emilio Martinelli.<\/p>\n<p>Ventiquattro fotografie fuori testo<\/p>\n<p>Edizione: 2021<\/p>\n<p>Ristampa: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>una storia di vita e di mare<\/p>\n<p class=\"autore\"><span>Author: <\/span>giovanni soldini<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>TEA &#8211; Tascabili degli Editori Associati<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788850262342<\/p>\n","protected":false},"featured_media":142764,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2971],"product_tag":[],"class_list":{"0":"post-88046","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-biographies-memories-and-interviews","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>nel blu - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nel blu\" \/>\n<meta property=\"og:description\" content=\"Subtitle: una storia di vita e di mareAuthor: giovanni soldiniPublisher: TEA - Tascabili degli Editori AssociatiISBN: 9788850262342\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:36:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/\",\"name\":\"nel blu - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/nel-blu-giovanni-soldini-4.jpg\",\"datePublished\":\"2022-02-02T14:00:41+00:00\",\"dateModified\":\"2026-05-09T00:36:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/nel-blu-giovanni-soldini-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/nel-blu-giovanni-soldini-4.jpg\",\"width\":500,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/nel-blu-giovanni-soldini-9788850262342\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"nel blu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788850262342\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"nel blu - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/","og_locale":"en_US","og_type":"article","og_title":"nel blu","og_description":"Subtitle: una storia di vita e di mareAuthor: giovanni soldiniPublisher: TEA - Tascabili degli Editori AssociatiISBN: 9788850262342","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:36:49+00:00","og_image":[{"width":500,"height":768,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/","name":"nel blu - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4.jpg","datePublished":"2022-02-02T14:00:41+00:00","dateModified":"2026-05-09T00:36:49+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4.jpg","width":500,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/nel-blu-giovanni-soldini-9788850262342\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"nel blu"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788850262342","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/nel-blu-giovanni-soldini-4-195x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/88046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=88046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142764"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=88046"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=88046"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=88046"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=88046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}