{"id":88024,"date":"2019-02-03T19:31:44","date_gmt":"2019-02-03T18:31:44","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/"},"modified":"2026-05-09T02:36:34","modified_gmt":"2026-05-09T00:36:34","slug":"gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/","title":{"rendered":"gli avventurosi viaggi del capitano voss"},"content":{"rendered":"<p>Un classico delle esplorazioni di mare, da pi&ugrave; di cinquant&#8217;anni assente dalle librerie: la pionieristica traversata dei tre oceani a bordo di una piccola imbarcazione. Nel maggio del 1901 John Claus Voss, accompagnato dal giornalista Norman Luxton, lascia il porto canadese di Victoria, nella Columbia Britannica, per un tentativo senza precedenti: la traversata dei tre grandi oceani a bordo di una piccola imbarcazione. &Egrave; ancora grande l&#8217;eco dell&#8217;impresa di Slocum sullo &#8220;Spray&#8221; e Voss decide di lanciare una sfida ancora pi&ugrave; ardua. La sua barca, la &#8220;Tilikum&#8221;, &egrave; infatti una piroga da guerra indiana scavata in un tronco, lunga poco pi&ugrave; di undici metri. A bordo di questo minuscolo scafo, Voss attraversa il Pacifico, poi raggiunge l&#8217;Australia e la Nuova Zelanda,&nbsp;affronta l&#8217;Oceano Indiano e l&#8217;Atlantico fino al Brasile, completando il suo periplo tre anni pi&ugrave; tardi, nel 1904, a Londra. Il lungo viaggio diventa anche un laboratorio per individuare le tecniche pi&ugrave; efficaci per sopravvivere alle tempeste in alto mare, teorie e accorgimenti pratici che il grande navigatore illustra in dettaglio nel corso della narrazione e in un&#8217;appendice al libro e che ancora oggi sono riconosciuti per la loro validit&agrave;.<\/p>\n<p>Edizione: 2014<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>voss j.c.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Nutrimenti Mare (Nutrimenti)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865943281<\/p>\n","protected":false},"featured_media":153800,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805],"product_tag":[],"class_list":{"0":"post-88024","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>gli avventurosi viaggi del capitano voss - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gli avventurosi viaggi del capitano voss\" \/>\n<meta property=\"og:description\" content=\"Author: voss j.c.Publisher: Nutrimenti Mare (Nutrimenti)ISBN: 9788865943281\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T00:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"416\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/\",\"name\":\"gli avventurosi viaggi del capitano voss - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventurosiviaggidelcapitanovoss-2.jpg\",\"datePublished\":\"2019-02-03T18:31:44+00:00\",\"dateModified\":\"2026-05-09T00:36:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventurosiviaggidelcapitanovoss-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/avventurosiviaggidelcapitanovoss-2.jpg\",\"width\":416,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"gli avventurosi viaggi del capitano voss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865943281\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"gli avventurosi viaggi del capitano voss - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/","og_locale":"en_US","og_type":"article","og_title":"gli avventurosi viaggi del capitano voss","og_description":"Author: voss j.c.Publisher: Nutrimenti Mare (Nutrimenti)ISBN: 9788865943281","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T00:36:34+00:00","og_image":[{"width":416,"height":608,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/","name":"gli avventurosi viaggi del capitano voss - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2.jpg","datePublished":"2019-02-03T18:31:44+00:00","dateModified":"2026-05-09T00:36:34+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2.jpg","width":416,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gli-avventurosi-viaggi-del-capitano-voss-voss-j-c-9788865943281\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"gli avventurosi viaggi del capitano voss"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788865943281","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/avventurosiviaggidelcapitanovoss-2-205x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/88024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=88024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/153800"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=88024"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=88024"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=88024"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=88024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}